{"id":4513,"date":"2026-01-02T01:08:38","date_gmt":"2026-01-02T01:08:38","guid":{"rendered":"https:\/\/www.pipetechservice.com\/?p=4513"},"modified":"2026-06-20T01:39:07","modified_gmt":"2026-06-20T01:39:07","slug":"a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project","status":"publish","type":"post","link":"https:\/\/www.pipetechservice.com\/ar\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/","title":{"rendered":"\u0633\u062c\u0644 \u0643\u0627\u0645\u0644 \u0644\u0644\u0636\u063a\u0637 \u0627\u0644\u0639\u0627\u0644\u064a \u0648\u062f\u0631\u062c\u0629 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u0645\u0631\u062a\u0641\u0639\u0629 \u0641\u064a \u0645\u0634\u0631\u0648\u0639 \u0645\u062d\u0637\u0629 \u0646\u064a\u0646\u063a\u0628\u0648 \u0644\u0644\u063a\u0627\u0632 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0627\u0644\u0645\u0633\u0627\u0644 EPC \u0644\u0645\u062d\u0637\u0629 \u0646\u064a\u0646\u063a\u0628\u0648 \u0644\u0644\u063a\u0627\u0632 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0627\u0644\u0645\u0633\u0627\u0644\u00a0"},"content":{"rendered":"<h2 class=\"wp-block-heading\" id=\"h-project-snapshot\"><strong>\u0644\u0645\u062d\u0629 \u0639\u0646 \u0627\u0644\u0645\u0634\u0631\u0648\u0639:<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>\u0627\u0644\u0641\u0626\u0629<\/th><th>\u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644<\/th><\/tr><\/thead><tbody><tr><td><strong>\u0627\u0644\u0639\u0645\u064a\u0644<\/strong><\/td><td>\u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u062f\u0648\u0644\u064a\u0629 \u0627\u0644\u0643\u0628\u0631\u0649 (\u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621)<\/td><\/tr><tr><td><strong>\u0627\u0644\u0645\u0648\u0642\u0639<\/strong><\/td><td>\u0646\u064a\u0646\u063a\u0628\u0648\u060c \u0627\u0644\u0635\u064a\u0646<\/td><\/tr><tr><td><strong>\u0627\u0644\u062a\u062d\u062f\u064a \u0627\u0644\u0623\u0633\u0627\u0633\u064a<\/strong><\/td><td>\u062a\u0646\u0641\u064a\u0630 12 \u0635\u0646\u0628\u0648\u0631\u064b\u0627 \u0633\u0627\u062e\u0646\u064b\u0627 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u063a\u0627\u0632 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0627\u0644\u062d\u064a\u0629 \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u0636\u063a\u0637 (7.0 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644) \u0648\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0632\u064a\u062a \u0627\u0644\u062d\u0631\u0627\u0631\u064a \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 (300 \u062f\u0631\u062c\u0629 \u0645\u0626\u0648\u064a\u0629) \u0627\u0644\u0645\u0635\u0646\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0641\u0648\u0644\u0627\u0630 \u0639\u0627\u0644\u064a \u0627\u0644\u062c\u0648\u062f\u0629 (X60\/L415Q) \u0628\u062c\u062f\u0631\u0627\u0646 \u0633\u0645\u064a\u0643\u0629 \u063a\u064a\u0631 \u0642\u064a\u0627\u0633\u064a\u0629\u060c \u062f\u0648\u0646 \u0625\u063a\u0644\u0627\u0642.<\/td><\/tr><tr><td><strong>\u062d\u0644\u0648\u0644 JSW<\/strong><\/td><td>\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0627\u0644\u0645\u0635\u0645\u0645\u0629 \u062d\u0633\u0628 \u0627\u0644\u0637\u0644\u0628\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u062a\u0635\u0645\u064a\u0645\/\u062a\u0635\u0646\u064a\u0639 \u062a\u062c\u0647\u064a\u0632\u0627\u062a \u0627\u0644\u062e\u062f\u0645\u0629 \u0627\u0644\u0634\u0627\u0642\u0629\u060c \u0648\u0625\u062c\u0631\u0627\u0621\u0627\u062a \u0627\u0644\u0644\u062d\u0627\u0645 \u0627\u0644\u0635\u0627\u0631\u0645\u0629\u060c \u0648\u0646\u0634\u0631 \u0645\u0639\u062f\u0627\u062a \u0627\u0644\u062d\u0641\u0631 \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u0633\u0639\u0629 \u0627\u0644\u062e\u0627\u0635\u0629. \u062e\u062f\u0645\u0629 \u062f\u0639\u0645 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0625\u0646\u0634\u0627\u0621\u0627\u062a \u0643\u0627\u0645\u0644\u0629 \u0627\u0644\u0646\u0637\u0627\u0642.<\/td><\/tr><tr><td><strong>\u0627\u0644\u0646\u062a\u0627\u0626\u062c \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/strong><\/td><td>\u0644\u0645 \u064a\u062a\u0645 \u062a\u062d\u0642\u064a\u0642 \u0623\u064a \u0625\u064a\u0642\u0627\u0641 \u062a\u0634\u063a\u064a\u0644. \u0645\u0639\u062f\u0644 \u0646\u062c\u0627\u062d 100% \u0639\u0644\u0649 \u062c\u0645\u064a\u0639 \u0627\u0644\u062a\u0648\u0635\u064a\u0644\u0627\u062a. \u0633\u062c\u0644 \u0633\u0644\u0627\u0645\u0629 \u0644\u0627 \u062a\u0634\u0648\u0628\u0647 \u0634\u0627\u0626\u0628\u0629. \u0636\u0645\u0627\u0646 \u0627\u0644\u062c\u062f\u0648\u0644 \u0627\u0644\u0632\u0645\u0646\u064a \u0644\u062a\u0648\u0633\u0639\u0629 \u0627\u0644\u0639\u0645\u064a\u0644 \u0648\u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u0633\u062a\u0645\u0631.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u062a\u062d\u062f\u064a \u0627\u0644\u0645\u0634\u0631\u0648\u0639: \u0625\u062c\u0631\u0627\u0621 \u201c\u0639\u0645\u0644\u064a\u0629 \u062c\u0631\u0627\u062d\u064a\u0629 \u0644\u062a\u062d\u0648\u064a\u0644 \u0645\u0633\u0627\u0631 \u0627\u0644\u0642\u0644\u0628\u201d \u0639\u0644\u0649 \u201c\u0634\u0631\u064a\u0627\u0646 \u0637\u0627\u0642\u0629 \u062d\u064a\u201d<\/strong><\/h2>\n\n\n\n<p>\u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0623\u064a \u0645\u062d\u0637\u0629 \u0631\u0626\u064a\u0633\u064a\u0629 \u0644\u0627\u0633\u062a\u0642\u0628\u0627\u0644 \u0627\u0644\u063a\u0627\u0632 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0627\u0644\u0645\u0633\u0627\u0644\u060c \u064a\u0639\u062a\u0628\u0631 \u0646\u0638\u0627\u0645 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u062f\u0627\u062e\u0644\u064a\u0629 \u201c\u0634\u0631\u064a\u0627\u0646 \u0627\u0644\u0637\u0627\u0642\u0629\u201d \u0627\u0644\u062d\u064a\u0648\u064a \u062d\u064a\u062b \u0644\u0627 \u064a\u0639\u062f \u0627\u0644\u0641\u0634\u0644 \u062e\u064a\u0627\u0631\u064b\u0627. \u0639\u0646\u062f\u0645\u0627 \u0642\u0627\u0645 \u0639\u0645\u064a\u0644\u0646\u0627 - \u0634\u0631\u0643\u0629 \u0637\u0627\u0642\u0629 \u062f\u0648\u0644\u064a\u0629 \u0631\u0627\u0626\u062f\u0629 - \u0628\u062a\u0637\u0648\u064a\u0631 \u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u062a\u0648\u0633\u0639\u0629 \u0648\u0627\u0644\u062a\u0639\u062f\u064a\u0644 \u0641\u064a \u0627\u0644\u0645\u0631\u062d\u0644\u0629 \u0627\u0644\u062b\u0627\u0644\u062b\u0629 \u0645\u0646 \u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u062a\u0648\u0633\u0639\u0629 \u0648\u0627\u0644\u062a\u0639\u062f\u064a\u0644 \u0641\u064a \u0645\u062d\u0637\u0629 \u0646\u064a\u0646\u063a\u0628\u0648 \u0627\u0644\u062a\u0627\u0628\u0639\u0629 \u0644\u0647\u0627\u060c \u0648\u0627\u062c\u0647\u062a \u0627\u0644\u0634\u0631\u0643\u0629 \u062a\u062d\u062f\u064a\u064b\u0627 \u062d\u0627\u0633\u0645\u064b\u0627 \u0641\u064a \u062a\u0639\u062f\u064a\u0644 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628: \u0625\u0636\u0627\u0641\u0629 \u0648\u0635\u0644\u0627\u062a \u062c\u062f\u064a\u062f\u0629 \u0625\u0644\u0649 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u062d\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u062d\u0645\u0644 \u0632\u064a\u062a\u064b\u0627 \u062d\u0631\u0627\u0631\u064a\u064b\u0627 \u0628\u062f\u0631\u062c\u0629 \u062d\u0631\u0627\u0631\u0629 300 \u062f\u0631\u062c\u0629 \u0645\u0626\u0648\u064a\u0629 \u0648\u063a\u0627\u0632\u064b\u0627 \u0637\u0628\u064a\u0639\u064a\u064b\u0627 \u0639\u0627\u0644\u064a \u0627\u0644\u0636\u063a\u0637 (\u062d\u062a\u0649 7.0 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644) \u062f\u0648\u0646 \u0625\u063a\u0644\u0627\u0642 \u0648\u0627\u062d\u062f.<\/p>\n\n\n\n<p>\u0643\u0627\u0646 \u0627\u0644\u0625\u063a\u0644\u0627\u0642 \u0627\u0644\u0643\u0627\u0645\u0644 \u064a\u0639\u0646\u064a \u062e\u0633\u0627\u0626\u0631 \u0625\u0646\u062a\u0627\u062c\u064a\u0629 \u0645\u0630\u0647\u0644\u0629 \u062a\u064f\u0642\u0627\u0633 \u0628\u0627\u0644\u0645\u0644\u0627\u064a\u064a\u0646 \u064a\u0648\u0645\u064a\u064b\u0627. \u0643\u0627\u0646\u062a \u0627\u0644\u0639\u0642\u0628\u0627\u062a \u0627\u0644\u062a\u0642\u0646\u064a\u0629 \u0647\u0627\u0626\u0644\u0629:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0627\u0644\u0645\u0639\u0644\u0645\u0627\u062a \u0627\u0644\u0642\u0635\u0648\u0649:<\/strong>\u00a0\u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0627\u0644\u0645\u062a\u0632\u0627\u0645\u0646 \u0628\u062f\u0631\u062c\u0629 \u062d\u0631\u0627\u0631\u0629 \u0639\u0627\u0644\u064a\u0629 (300 \u062f\u0631\u062c\u0629 \u0645\u0626\u0648\u064a\u0629) \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0627\u0644\u0632\u064a\u062a \u0627\u0644\u062d\u0631\u0627\u0631\u064a \u0648\u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0639\u0627\u0644\u064a \u0627\u0644\u0636\u063a\u0637 (7.0 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644) \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0627\u0644\u063a\u0627\u0632.<\/li>\n\n\n\n<li><strong>\u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u0645\u0637\u0644\u0648\u0628\u0629:<\/strong>\u00a0\u0627\u0644\u0639\u0645\u0644 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0641\u0648\u0644\u0627\u0630\u064a\u0629 \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 (X60\u060c L415Q) \u0628\u0623\u0642\u0637\u0627\u0631 \u063a\u064a\u0631 \u0642\u064a\u0627\u0633\u064a\u0629 (D717\u060c D660) \u0648\u062c\u062f\u0631\u0627\u0646 \u0633\u0645\u064a\u0643\u0629 \u0644\u0644\u063a\u0627\u064a\u0629 (\u062d\u062a\u0649 30 \u0645\u0645 \u0623\u0646\u0627\u0628\u064a\u0628\u060c \u062a\u0639\u0632\u064a\u0632\u0627\u062a \u062a\u0631\u0643\u064a\u0628\u0627\u062a 50 \u0645\u0645).<\/li>\n\n\n\n<li><strong>\u0627\u0644\u0647\u0627\u0645\u0634 \u0627\u0644\u0635\u0641\u0631\u064a \u0644\u0644\u062e\u0637\u0623:<\/strong>\u00a0\u0643\u0627\u0646\u062a \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0639\u0644\u0649 \u0628\u0646\u064a\u0629 \u062a\u062d\u062a\u064a\u0629 \u062d\u0631\u062c\u0629 \u062d\u064a\u062b \u0643\u0627\u0646\u062a \u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0648\u0627\u0644\u0646\u0632\u0627\u0647\u0629 \u0623\u0645\u0631\u064b\u0627 \u0628\u0627\u0644\u063a \u0627\u0644\u0623\u0647\u0645\u064a\u0629. \u0623\u064a \u062e\u0644\u0644 \u0641\u064a \u0627\u0644\u0644\u062d\u0627\u0645 \u0623\u0648 \u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u062d\u0641\u0631 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u0624\u062f\u064a \u0625\u0644\u0649 \u0641\u0634\u0644 \u0643\u0627\u0631\u062b\u064a.<\/li>\n<\/ul>\n\n\n\n<p>\u0644\u0642\u062f \u0627\u062d\u062a\u0627\u062c\u0648\u0627 \u0625\u0644\u0649 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0645\u062c\u0631\u062f \u0645\u0642\u0627\u0648\u0644\u061b \u0641\u0642\u062f \u0627\u062d\u062a\u0627\u062c\u0648\u0627 \u0625\u0644\u0649 \u0634\u0631\u064a\u0643 \u064a\u062a\u0645\u062a\u0639 \u0628\u062e\u0628\u0631\u0629 \u0645\u062b\u0628\u062a\u0629 \u0641\u064a \u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0627\u0644\u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0642\u0627\u062f\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0645\u062b\u0644 \u0647\u0630\u0627 \u0627\u0644\u0646\u0637\u0627\u0642 \u0627\u0644\u0645\u0639\u0642\u062f \u0645\u0646 \u0623\u0639\u0645\u0627\u0644 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621. \u0648\u0647\u0646\u0627 \u062a\u0645 \u0627\u0644\u062a\u0639\u0627\u0642\u062f \u0645\u0639 \u0634\u0631\u0643\u0629 JSW \u0644\u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-809ae73a alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a4135039\">\n<div class=\"wp-block-uagb-image uagb-block-366f3850 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Equipment-Installation-for-Pipeline-Modification-in-EPC-Project.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Equipment-Installation-for-Pipeline-Modification-in-EPC-Project.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Equipment-Installation-for-Pipeline-Modification-in-EPC-Project.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Equipment-Installation-for-Pipeline-Modification-in-EPC-Project.jpg\" alt=\"\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0635\u0646\u0628\u0648\u0631 \u0627\u0644\u0623\u062d\u0645\u0631 \u0627\u0644\u0633\u0627\u062e\u0646 (\u0645\u0639 \u062a\u0631\u0643\u064a\u0628\u0627\u062a \u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u0627\u062a\u062c\u0627\u0647\u0627\u062a) \u0627\u0644\u062a\u064a \u064a\u062a\u0645 \u062a\u0631\u0643\u064a\u0628\u0647\u0627 \u0639\u0644\u0649 \u062e\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0635\u0646\u0627\u0639\u064a \u062e\u0644\u0627\u0644 \u0645\u0634\u0631\u0648\u0639 \u062a\u0639\u062f\u064a\u0644 \u062e\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 EPC\u060c \u0645\u0639 \u0648\u062c\u0648\u062f \u0639\u0645\u0627\u0644 \u0648\u0645\u0639\u062f\u0627\u062a \u0631\u0641\u0639 \u0641\u064a \u0627\u0644\u0645\u0648\u0642\u0639\" class=\"uag-image-4517\" width=\"800\" height=\"600\" title=\"\u062a\u0631\u0643\u064a\u0628 \u0645\u0639\u062f\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0639\u0644\u0649 \u0627\u0644\u0633\u0627\u062e\u0646 \u0644\u062a\u0639\u062f\u064a\u0644 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0641\u064a \u0645\u0634\u0631\u0648\u0639 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b906b3d8\">\n<div class=\"wp-block-uagb-image uagb-block-4fd1b156 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Pipeline-Hot-Tapping-Supporting-Facilities-in-EPC-Pipeline-Modification.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Pipeline-Hot-Tapping-Supporting-Facilities-in-EPC-Pipeline-Modification.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Pipeline-Hot-Tapping-Supporting-Facilities-in-EPC-Pipeline-Modification.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Pipeline-Hot-Tapping-Supporting-Facilities-in-EPC-Pipeline-Modification.jpg\" alt=\"\u0646\u0638\u0627\u0645 \u062e\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 (\u0645\u0639 \u0643\u0648\u0639) \u0645\u062a\u0635\u0644 \u0628\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646\u060c \u0645\u0639 \u0633\u0642\u0627\u0644\u0627\u062a \u0648\u0631\u0627\u0641\u0639\u0629 \u0641\u064a \u0645\u0648\u0642\u0639 \u062a\u0639\u062f\u064a\u0644 \u062e\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 EPC\" class=\"uag-image-4518\" width=\"800\" height=\"600\" title=\"\u0627\u0644\u0645\u0631\u0627\u0641\u0642 \u0627\u0644\u062f\u0627\u0639\u0645\u0629 \u0644\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0644\u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0641\u064a \u062a\u0639\u062f\u064a\u0644 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0641\u064a EPC\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0627\u0644\u062d\u0644 \u0627\u0644\u0630\u064a \u0646\u0642\u062f\u0645\u0647: \u0628\u0631\u0648\u062a\u0648\u0643\u0648\u0644 \u0647\u0646\u062f\u0633\u064a \u0645\u0635\u0645\u0645 \u062e\u0635\u064a\u0635\u064b\u0627 \u0644\u0644\u062a\u062f\u062e\u0644 \u0627\u0644\u0645\u0628\u0627\u0634\u0631 \u0627\u0644\u062f\u0642\u064a\u0642<\/strong><\/h2>\n\n\n\n<p>\u0648\u0628\u0627\u0639\u062a\u0628\u0627\u0631\u0647\u0627 \u0634\u0631\u0643\u0629 \u0645\u062a\u0639\u0627\u0642\u062f\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0648\u0645\u0635\u0646\u0639\u0629 \u0644\u0644\u0645\u0639\u062f\u0627\u062a \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629\u060c \u0644\u0645 \u062a\u062a\u0639\u0627\u0645\u0644 JSW \u0645\u0639 \u0647\u0630\u0627 \u0627\u0644\u0623\u0645\u0631 \u0643\u0645\u0647\u0645\u0629 \u0639\u0627\u062f\u064a\u0629\u060c \u0628\u0644 \u0643\u0645\u0634\u0631\u0648\u0639 \u0647\u0646\u062f\u0633\u064a. \u0643\u0627\u0646 \u062d\u0644\u0646\u0627 \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u0628\u0631\u0648\u062a\u0648\u0643\u0648\u0644 \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0637\u0628\u0642\u0627\u062a \u0645\u0635\u0645\u0645 \u062e\u0635\u064a\u0635\u064b\u0627:<\/p>\n\n\n\n<p><strong>1. \u0627\u0644\u062a\u0631\u0643\u064a\u0628\u0627\u062a \u0627\u0644\u0647\u0646\u062f\u0633\u064a\u0629 \u0648\u0627\u0644\u0644\u062d\u0627\u0645 \u0627\u0644\u0645\u062a\u0642\u062f\u0645:<\/strong><br>\u0644\u0642\u062f \u0635\u0645\u0645\u0646\u0627 \u0648\u0635\u0646\u0639\u0646\u0627 \u062a\u064a\u0632\u064a\u0646\u0627\u062a \u0645\u0642\u0633\u0645\u0629 \u0643\u0627\u0645\u0644\u0629 \u0627\u0644\u062f\u0627\u0626\u0631\u0629 \u0645\u0639 \u0648\u0633\u0627\u062f\u0627\u062a \u062a\u0642\u0648\u064a\u0629 \u0628\u0633\u064f\u0645\u0643 50 \u0645\u0645 \u0644\u0644\u062a\u062d\u0643\u0645 \u0641\u064a \u0627\u0644\u0625\u062c\u0647\u0627\u062f. \u0642\u0627\u0645 \u0639\u0645\u0627\u0644 \u0627\u0644\u0644\u062d\u0627\u0645 \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0648\u0646 \u0644\u062f\u064a\u0646\u0627 \u0628\u062a\u0646\u0641\u064a\u0630 \u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0625\u062c\u0631\u0627\u0621\u0627\u062a \u0627\u0644\u0644\u062d\u0627\u0645 \u0627\u0644\u0635\u0627\u0631\u0645\u0629 (WPS) \u0644\u0645\u0648\u0627\u062f X60 \u0648L415Q\u060c \u0648\u0627\u0644\u062a\u064a \u062a\u062a\u0636\u0645\u0646 \u0627\u0644\u062a\u0633\u062e\u064a\u0646 \u0627\u0644\u0645\u0633\u0628\u0642\u060c \u0648\u0627\u0644\u062a\u062d\u0643\u0645 \u0641\u064a \u062f\u0631\u062c\u0629 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u0628\u064a\u0646\u064a\u0629\u060c \u0648\u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u062d\u0631\u0627\u0631\u064a\u0629 \u0644\u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0644\u062d\u0627\u0645 (PWHT) \u0639\u0646\u062f \u0627\u0644\u0636\u0631\u0648\u0631\u0629\u060c \u0648\u0643\u0644\u0647\u0627 \u062a\u0645\u062a \u0645\u0631\u0627\u0642\u0628\u062a\u0647\u0627 \u0648\u062a\u0648\u062b\u064a\u0642\u0647\u0627 \u0644\u0636\u0645\u0627\u0646 \u0633\u0644\u0627\u0645\u0629 \u0645\u0633\u0627\u0648\u064a\u0629 \u0644\u0644\u0623\u0646\u0628\u0648\u0628 \u0627\u0644\u0623\u0635\u0644\u064a.<\/p>\n\n\n\n<p><strong>2. \u0645\u0639\u062f\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0639\u0644\u0649 \u0627\u0644\u0633\u0627\u062e\u0646 \u0627\u0644\u0645\u0633\u062c\u0644\u0629 \u0627\u0644\u0645\u0644\u0643\u064a\u0629:<\/strong><br>\u0644\u0642\u062f \u0646\u0634\u0631\u0646\u0627 \u0645\u0627\u0643\u064a\u0646\u0627\u062a \u0627\u0644\u062b\u0642\u0628 \u0627\u0644\u0633\u0627\u062e\u0646 \u0630\u0627\u062a \u0627\u0644\u0623\u0634\u0648\u0627\u0637 \u0627\u0644\u0643\u0628\u064a\u0631\u0629 \u0648\u0639\u0632\u0645 \u0627\u0644\u062f\u0648\u0631\u0627\u0646 \u0627\u0644\u0639\u0627\u0644\u064a (\u0633\u0644\u0633\u0644\u0629 JSW-HT)\u060c \u0627\u0644\u0645\u0635\u0645\u0645\u0629 \u062e\u0635\u064a\u0635\u064b\u0627 \u0644\u062d\u0641\u0631 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0630\u0627\u062a \u0627\u0644\u062c\u062f\u0631\u0627\u0646 \u0627\u0644\u0633\u0645\u064a\u0643\u0629. \u0648\u062a\u062a\u0645\u064a\u0632 \u0647\u0630\u0647 \u0627\u0644\u0645\u0627\u0643\u064a\u0646\u0627\u062a \u0628\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0645\u0639\u0632\u0632\u0629 \u0644\u0644\u062b\u0628\u0627\u062a \u0648\u0623\u062f\u0627\u0629 \u0627\u0644\u0642\u0637\u0639 \u0644\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0627\u0644\u0641\u0648\u0644\u0627\u0630 \u0639\u0627\u0644\u064a \u0627\u0644\u062c\u0648\u062f\u0629 \u0628\u0643\u0641\u0627\u0621\u0629 \u0648\u0623\u0645\u0627\u0646 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u0627\u0644\u0643\u0627\u0645\u0644.<\/p>\n\n\n\n<p><strong>3. \u062e\u0637\u0629 \u062a\u0646\u0641\u064a\u0630 \u0635\u0627\u0631\u0645\u0629 \u0644\u062a\u062e\u0641\u064a\u0641 \u0627\u0644\u0645\u062e\u0627\u0637\u0631:<\/strong><br>\u0648\u0642\u062f \u0633\u0628\u0642 \u0643\u0644 \u0639\u0645\u0644\u064a\u0629 \u062d\u0641\u0631 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u0627\u0644\u0633\u0627\u062e\u0646 \u062a\u062d\u0644\u064a\u0644 \u0633\u0644\u0627\u0645\u0629 \u0627\u0644\u0639\u0645\u0644 (JSA) \u0648\u0625\u062c\u0631\u0627\u0621 \u201c\u0646\u0642\u0637\u0629 \u062a\u0648\u0642\u0641\u201d \u0645\u0641\u0635\u0644\u0629. \u0648\u0634\u0645\u0644\u062a \u0645\u0646\u0647\u062c\u064a\u062a\u0646\u0627 \u0644\u0644\u062d\u0641\u0631 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u0639\u0632\u0644 \u0627\u0644\u0635\u0645\u0627\u0645 \u0627\u0644\u0645\u0632\u062f\u0648\u062c\u060c \u0648\u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0627\u0644\u062b\u0642\u0628 \u0627\u0644\u062a\u062c\u0631\u064a\u0628\u064a\u060c \u0648\u0627\u0644\u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u0645\u0633\u062a\u0645\u0631\u0629 \u0644\u0644\u0636\u063a\u0637 \u0637\u0648\u0627\u0644 \u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u0642\u0637\u0639.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0627\u0644\u062a\u0646\u0641\u064a\u0630: \u062a\u0646\u0641\u064a\u0630 \u0644\u0627 \u062a\u0634\u0648\u0628\u0647 \u0634\u0627\u0626\u0628\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062f\u0642\u0629 \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629<\/strong><\/h2>\n\n\n\n<p>\u0648\u0642\u062f \u062a\u0636\u0645\u0646 \u062f\u0648\u0631\u0646\u0627 \u0643\u0634\u0631\u064a\u0643 \u0645\u062a\u062e\u0635\u0635 \u0641\u064a \u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0625\u0646\u0634\u0627\u0621\u0627\u062a \u0627\u0644\u062a\u0643\u0627\u0645\u0644 \u0627\u0644\u0633\u0644\u0633 \u0645\u0639 \u0627\u0644\u062c\u062f\u0648\u0644 \u0627\u0644\u0632\u0645\u0646\u064a \u0644\u0644\u0645\u0642\u0627\u0648\u0644 \u0627\u0644\u0631\u0626\u064a\u0633\u064a. \u0648\u0643\u0627\u0646\u062a \u0627\u0644\u0645\u0631\u0627\u062d\u0644 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629 \u0647\u064a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0627\u0644\u0645\u0631\u062d\u0644\u0629 1: \u0627\u0644\u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0645\u0646\u0627\u0633\u0628 \u0644\u0644\u063a\u0631\u0636.<\/strong>\u00a0\u0639\u0645\u0644\u064a\u0627\u062a \u0645\u0633\u062d \u0627\u0644\u0645\u0648\u0642\u0639\u060c \u0648\u062a\u0623\u0647\u064a\u0644 \u0627\u0644\u0625\u062c\u0631\u0627\u0621\u0627\u062a\u060c \u0648\u062a\u0631\u0643\u064a\u0628 \u0627\u0644\u062a\u0631\u0643\u064a\u0628\u0627\u062a \u0627\u0644\u0645\u062e\u0635\u0635\u0629 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0645\u062d\u0627\u0630\u0627\u0629 \u0627\u0644\u0644\u064a\u0632\u0631 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u062a\u0648\u062c\u064a\u0647 \u0645\u062b\u0627\u0644\u064a.<\/li>\n\n\n\n<li><strong>\u0627\u0644\u0645\u0631\u062d\u0644\u0629 2: \u062d\u0645\u0644\u0629 \u0627\u0644\u0644\u062d\u0627\u0645 \u0627\u0644\u062d\u0631\u062c\u0629.<\/strong>\u00a0\u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0644\u062d\u0627\u0645\u0627\u062a \u0630\u0627\u062a \u0627\u0644\u062c\u062f\u0631\u0627\u0646 \u0627\u0644\u0633\u0645\u064a\u0643\u0629 \u062a\u062d\u062a \u0638\u0631\u0648\u0641 \u062e\u0627\u0636\u0639\u0629 \u0644\u0644\u0631\u0642\u0627\u0628\u0629\u060c \u0645\u062a\u0628\u0648\u0639\u064b\u0627 \u0628\u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631 \u063a\u064a\u0631 \u0627\u0644\u0645\u062a\u0644\u0641 100% \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631 \u0628\u0627\u0644\u0645\u0648\u062c\u0627\u062a \u0641\u0648\u0642 \u0627\u0644\u0635\u0648\u062a\u064a\u0629 (UT) \u0648\u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631 \u0627\u0644\u0625\u0634\u0639\u0627\u0639\u064a (RT).<\/li>\n\n\n\n<li><strong>\u0627\u0644\u0645\u0631\u062d\u0644\u0629 3: \u0627\u0644\u062d\u0646\u0641\u064a\u0629 \u0627\u0644\u062d\u064a\u0629.<\/strong>\u00a0\u062a\u0631\u0643\u064a\u0628 \u0622\u0644\u0629 \u0627\u0644\u062b\u0642\u0628 \u0648\u0627\u062e\u062a\u0628\u0627\u0631 \u0636\u063a\u0637 \u0627\u0644\u062a\u062c\u0645\u064a\u0639 \u0648\u0625\u062c\u0631\u0627\u0621 \u0627\u0644\u062b\u0642\u0628 \u0627\u0644\u0633\u0627\u062e\u0646 \u0644\u062e\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628. \u0643\u0627\u0646\u062a \u0639\u0645\u0644\u064a\u0629 \u062b\u0642\u0628 \u062e\u0637 \u0627\u0644\u063a\u0627\u0632 \u0639\u0627\u0644\u064a \u0627\u0644\u0636\u063a\u0637 D717 \u0644\u062d\u0638\u0629 \u0641\u0627\u0631\u0642\u0629 \u0641\u064a \u0627\u0644\u062d\u0641\u0631\u060c \u062d\u064a\u062b \u062a\u0637\u0644\u0628\u062a \u062a\u062d\u0643\u0645\u064b\u0627 \u062f\u0642\u064a\u0642\u064b\u0627 \u062d\u064a\u062b \u0627\u062e\u062a\u0631\u0642 \u0627\u0644\u0642\u0627\u0637\u0639 \u0627\u0644\u0641\u0648\u0644\u0627\u0630 X60 \u0628\u0633\u0645\u0643 19.1 \u0645\u0645 \u062a\u062d\u062a \u0636\u063a\u0637 7.0 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644.<\/li>\n\n\n\n<li><strong>\u0627\u0644\u0645\u0631\u062d\u0644\u0629 4: \u0627\u0644\u0625\u0646\u062c\u0627\u0632 \u0648\u0627\u0644\u062a\u0633\u0644\u064a\u0645.<\/strong>\u00a0\u0627\u0633\u062a\u0631\u062c\u0627\u0639 \u0627\u0644\u0645\u0627\u0643\u064a\u0646\u0629\u060c \u0648\u062a\u0631\u0643\u064a\u0628 \u0633\u062f\u0627\u062f\u0629 \u0627\u0644\u0625\u0643\u0645\u0627\u0644\u060c \u0648\u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631 \u0627\u0644\u0646\u0647\u0627\u0626\u064a\u060c \u0648\u062a\u0637\u0628\u064a\u0642 \u0637\u0644\u0627\u0621 \u0627\u0644\u062a\u0622\u0643\u0644. \u062a\u0645 \u0627\u062d\u062a\u0648\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0646\u0641\u0627\u064a\u0627\u062a (\u0627\u0644\u0643\u0648\u0628\u0648\u0646\u0627\u062a) \u0648\u0625\u0632\u0627\u0644\u062a\u0647\u0627 \u0628\u0623\u0645\u0627\u0646.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-49c0b3bf alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-924f037b\">\n<div class=\"wp-block-uagb-image uagb-block-f0da1dd9 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Device-Integrated-in-Pipeline-System-of-EPC-Modification-Project.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Device-Integrated-in-Pipeline-System-of-EPC-Modification-Project.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Device-Integrated-in-Pipeline-System-of-EPC-Modification-Project.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Hot-Tapping-Device-Integrated-in-Pipeline-System-of-EPC-Modification-Project.jpg\" alt=\"\u062c\u0647\u0627\u0632 \u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0623\u062d\u0645\u0631 \u0627\u0644\u0633\u0627\u062e\u0646 \u0627\u0644\u0645\u062f\u0645\u062c \u0645\u0639 \u0646\u0638\u0627\u0645 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629 \u0641\u064a \u0645\u0648\u0642\u0639 \u0645\u0634\u0631\u0648\u0639 \u062a\u0639\u062f\u064a\u0644 \u062e\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 EPC\" class=\"uag-image-4519\" width=\"800\" height=\"600\" title=\"\u062c\u0647\u0627\u0632 \u0627\u0644\u062a\u0646\u0635\u062a \u0639\u0644\u0649 \u0627\u0644\u0633\u0627\u062e\u0646 \u0627\u0644\u0645\u062f\u0645\u062c \u0641\u064a \u0646\u0638\u0627\u0645 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0644\u0645\u0634\u0631\u0648\u0639 \u062a\u0639\u062f\u064a\u0644 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a33e4dbc\">\n<div class=\"wp-block-uagb-image uagb-block-cd9032eb wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/On-site-Operation-of-Hot-Tapping-Equipment-in-EPC-Pipeline-Services.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/On-site-Operation-of-Hot-Tapping-Equipment-in-EPC-Pipeline-Services.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/On-site-Operation-of-Hot-Tapping-Equipment-in-EPC-Pipeline-Services.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/On-site-Operation-of-Hot-Tapping-Equipment-in-EPC-Pipeline-Services.jpg\" alt=\"\u0639\u0645\u0627\u0644 \u064a\u0642\u0648\u0645\u0648\u0646 \u0628\u062a\u0634\u063a\u064a\u0644 \u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0631\u0641\u0639 \u0644\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0641\u064a \u062a\u0631\u0643\u064a\u0628 \u0645\u0639\u062f\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0639\u0644\u0649 \u062e\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0636\u063a\u0637 \u0627\u0644\u0639\u0627\u0644\u064a \u0623\u062b\u0646\u0627\u0621 \u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 EPC\" class=\"uag-image-4520\" width=\"600\" height=\"800\" title=\"\u0627\u0644\u062a\u0634\u063a\u064a\u0644 \u0641\u064a \u0627\u0644\u0645\u0648\u0642\u0639 \u0644\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0639\u0644\u0649 \u0627\u0644\u0633\u0627\u062e\u0646 \u0641\u064a \u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0627\u0644\u0646\u062a\u0627\u0626\u062c \u0648\u0627\u0644\u0641\u0648\u0627\u0626\u062f: \u062a\u0642\u062f\u064a\u0645 \u0642\u064a\u0645\u0629 \u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u0642\u064a\u0627\u0633 \u0627\u0644\u0643\u0645\u064a \u062e\u0627\u0631\u062c \u0646\u0637\u0627\u0642 \u0627\u0644\u0645\u0647\u0645\u0629<\/strong><\/h2>\n\n\n\n<p>\u062a\u0645 \u0642\u064a\u0627\u0633 \u0646\u062c\u0627\u062d \u062e\u062f\u0645\u0629 \u062a\u0639\u062f\u064a\u0644 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0647\u0630\u0647 \u0645\u0646 \u062d\u064a\u062b \u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0648\u0627\u0644\u0645\u0648\u062b\u0648\u0642\u064a\u0629 \u0648\u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0627\u062a.<\/p>\n\n\n\n<p><strong>\u0627\u0644\u0646\u062a\u0627\u0626\u062c \u0627\u0644\u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u0642\u064a\u0627\u0633 \u0627\u0644\u0643\u0645\u064a:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0627\u0646\u0639\u062f\u0627\u0645 \u062d\u0648\u0627\u062f\u062b \u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0623\u0648 \u0627\u0644\u062d\u0648\u0627\u062f\u062b \u0627\u0644\u0628\u064a\u0626\u064a\u0629:<\/strong>\u00a0\u0633\u062c\u0644 \u0645\u062b\u0627\u0644\u064a \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0635\u062d\u0629 \u0648\u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0648\u0627\u0644\u0628\u064a\u0626\u0629 \u0641\u064a \u062c\u0645\u064a\u0639 \u0645\u0631\u0627\u062d\u0644 \u0627\u0644\u0645\u0634\u0631\u0648\u0639.<\/li>\n\n\n\n<li><strong>100% \u0627\u0633\u062a\u0645\u0631\u0627\u0631\u064a\u0629 \u0627\u0644\u062a\u0634\u063a\u064a\u0644:<\/strong>\u00a0\u062a\u0645 \u0627\u0644\u0627\u0646\u062a\u0647\u0627\u0621 \u0645\u0646 \u062c\u0645\u064a\u0639 \u0627\u0644\u0635\u0646\u0627\u0628\u064a\u0631 \u0627\u0644 12 \u0627\u0644\u0633\u0627\u062e\u0646\u0629 \u062f\u0648\u0646 \u0627\u0644\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0625\u064a\u0642\u0627\u0641 \u0627\u0644\u062a\u0634\u063a\u064a\u0644\u060c \u0645\u0645\u0627 \u0648\u0641\u0631 \u0639\u0644\u0649 \u0627\u0644\u0639\u0645\u064a\u0644 \u062e\u0633\u0627\u0631\u0629 \u062a\u0642\u062f\u0631 \u0628\u0645\u0644\u0627\u064a\u064a\u0646 \u0627\u0644\u062f\u0648\u0644\u0627\u0631\u0627\u062a \u0641\u064a \u0648\u0642\u062a \u062a\u0639\u0637\u0644 \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0645\u062d\u062a\u0645\u0644.<\/li>\n\n\n\n<li><strong>100% \u0645\u0639\u062f\u0644 \u0627\u0644\u0646\u062c\u0627\u062d 100%<\/strong>\u00a0\u062a\u0645 \u0627\u0644\u0627\u0646\u062a\u0647\u0627\u0621 \u0645\u0646 \u062c\u0645\u064a\u0639 \u0627\u0644\u062a\u0648\u0635\u064a\u0644\u0627\u062a \u0641\u064a \u0627\u0644\u0645\u0648\u0639\u062f \u0627\u0644\u0645\u062d\u062f\u062f\u060c \u0648\u0627\u062c\u062a\u0627\u0632\u062a \u062c\u0645\u064a\u0639 \u0627\u062e\u062a\u0628\u0627\u0631\u0627\u062a \u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0648\u0647\u064a \u062a\u0639\u0645\u0644 \u0628\u0643\u0627\u0645\u0644 \u0637\u0627\u0642\u062a\u0647\u0627.<\/li>\n\n\n\n<li><strong>\u062a\u0635\u0645\u064a\u0645 \u064a\u0648\u0627\u0643\u0628 \u0627\u0644\u0645\u0633\u062a\u0642\u0628\u0644:<\/strong>\u00a0\u062a\u0636\u0645\u0646 \u062a\u062c\u0647\u064a\u0632\u0627\u062a \u0627\u0644\u062a\u062c\u0647\u064a\u0632\u0627\u062a \u0627\u0644\u0645\u062b\u0628\u062a\u0629 \u0627\u0644\u0645\u0632\u0648\u062f\u0629 \u0628\u0645\u0631\u0634\u062d\u0627\u062a \u062f\u0627\u062e\u0644\u064a\u0629 \u0644\u0644\u062d\u0637\u0627\u0645 \u0639\u062f\u0645 \u0627\u0644\u062a\u062f\u0627\u062e\u0644 \u0645\u0639 \u0645\u0642\u0627\u064a\u064a\u0633 \u0641\u062d\u0635 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 (PIGs) \u0641\u064a \u0627\u0644\u0645\u0633\u062a\u0642\u0628\u0644.<\/li>\n<\/ul>\n\n\n\n<p><strong>\u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u0639\u0645\u0644\u0627\u0621:<\/strong><br><em>\u201c\u0623\u062f\u0627\u0631 \u0641\u0631\u064a\u0642 JSW \u0623\u0643\u062b\u0631 \u062a\u062f\u062e\u0644\u0627\u062a \u062e\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0623\u0647\u0645\u064a\u0629 \u0644\u062f\u064a\u0646\u0627 \u0628\u0627\u062d\u062a\u0631\u0627\u0641\u064a\u0629 \u0645\u062a\u0645\u064a\u0632\u0629. \u0643\u0627\u0646\u062a \u0642\u062f\u0631\u062a\u0647\u0645 \u0627\u0644\u0645\u0632\u062f\u0648\u062c\u0629 \u0643\u0635\u0627\u0646\u0639\u064a \u0645\u0639\u062f\u0627\u062a \u0648\u0645\u062a\u062e\u0635\u0635\u064a\u0646 \u0645\u064a\u062f\u0627\u0646\u064a\u064a\u0646 \u0648\u0627\u0636\u062d\u0629. \u0641\u0642\u062f \u0635\u0645\u0645\u0648\u0627 \u062d\u0644\u0648\u0644\u0627\u064b \u0647\u0646\u062f\u0633\u064a\u0629 \u0644\u0635\u0646\u0627\u0628\u064a\u0631\u0646\u0627 \u0627\u0644\u0641\u0631\u064a\u062f\u0629 \u0630\u0627\u062a \u0627\u0644\u062c\u062f\u0631\u0627\u0646 \u0627\u0644\u0633\u0645\u064a\u0643\u0629 \u0648\u0627\u0644\u0636\u063a\u0637 \u0627\u0644\u0639\u0627\u0644\u064a\u060c \u0648\u0644\u0645 \u064a\u0643\u062a\u0641\u0648\u0627 \u0628\u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u0642\u064a\u0627\u0633\u064a\u0629. \u0648\u0642\u062f \u0636\u0645\u0646 \u0639\u0645\u0644\u0647\u0645 \u0628\u0642\u0627\u0621 \u062a\u0648\u0633\u0639\u0627\u062a\u0646\u0627 \u0639\u0644\u0649 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0635\u062d\u064a\u062d \u062f\u0648\u0646 \u062a\u0639\u0637\u064a\u0644 \u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0645\u062d\u0637\u0629 \u0648\u0644\u0648 \u0644\u062f\u0642\u064a\u0642\u0629 \u0648\u0627\u062d\u062f\u0629.\u201d<\/em><br>\u2014&nbsp;<strong>\u0645\u062f\u064a\u0631 \u0645\u0634\u0631\u0648\u0639\u060c \u0641\u0631\u064a\u0642 \u0627\u0644\u0639\u0645\u064a\u0644 \u0644\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0644\u0645\u0627\u0630\u0627 \u062a\u064f\u0639\u062f \u0634\u0631\u0643\u0629 JSW \u0644\u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0634\u0631\u064a\u0643\u0643 \u0627\u0644\u0645\u0648\u062b\u0648\u0642 \u0628\u0647<\/strong><\/h2>\n\n\n\n<p>\u064a\u062c\u0633\u062f \u0645\u0634\u0631\u0648\u0639 \u0645\u062d\u0637\u0629 \u0646\u064a\u0646\u063a\u0628\u0648 \u0647\u0630\u0627 \u062c\u0648\u0647\u0631 \u0634\u0631\u0643\u0629 JSW. \u0641\u0646\u062d\u0646 \u0644\u0633\u0646\u0627 \u0645\u062c\u0631\u062f \u0634\u0631\u0643\u0629 \u062e\u062f\u0645\u0627\u062a\u060c \u0628\u0644 \u0646\u062d\u0646 \u0634\u0631\u0643\u0629 \u0645\u0642\u0627\u0648\u0644\u0627\u062a \u0645\u062a\u0643\u0627\u0645\u0644\u0629 \u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627\u064b. \u0648\u0628\u0635\u0641\u062a\u0646\u0627 \u0645\u0635\u0646\u0639\u064a\u0646 \u0648\u0645\u0645\u0627\u0631\u0633\u064a\u0646 \u0639\u0644\u0649 \u062d\u062f \u0633\u0648\u0627\u0621\u060c \u0641\u0625\u0646\u0646\u0627 \u0646\u062a\u062d\u0643\u0645 \u0641\u064a \u0633\u0644\u0633\u0644\u0629 \u0627\u0644\u0642\u064a\u0645\u0629 \u0628\u0623\u0643\u0645\u0644\u0647\u0627 - \u0628\u062f\u0621\u064b\u0627 \u0645\u0646 \u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0644\u0639\u0645\u0644 \u0625\u0644\u0649 \u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u0645\u064a\u062f\u0627\u0646\u064a \u0628\u062e\u0628\u0631\u0629 \u0644\u0627 \u0645\u062b\u064a\u0644 \u0644\u0647\u0627.<\/p>\n\n\n\n<p><strong>\u062a\u0634\u0645\u0644 \u0645\u062c\u0645\u0648\u0639\u0629 \u062e\u062f\u0645\u0627\u062a\u0646\u0627 \u0645\u0627 \u064a\u0644\u064a:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0646\u0635\u062a \u0648\u0627\u0644\u062a\u0648\u0635\u064a\u0644 \u0627\u0644\u0633\u0627\u062e\u0646:<\/strong>\u00a0\u0644\u062c\u0645\u064a\u0639 \u0627\u0644\u0623\u0642\u0637\u0627\u0631 \u0648\u0627\u0644\u0636\u063a\u0648\u0637 \u0648\u0627\u0644\u0648\u0633\u0627\u0626\u0637.<\/li>\n\n\n\n<li><strong>\u0627\u0644\u0627\u0633\u062a\u062c\u0627\u0628\u0629 \u0644\u0637\u0648\u0627\u0631\u0626 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0648\u0625\u0635\u0644\u0627\u062d\u0647\u0627:<\/strong>\u00a0\u0627\u0644\u0627\u0633\u062a\u0639\u062f\u0627\u062f \u0639\u0644\u0649 \u0645\u062f\u0627\u0631 \u0627\u0644\u0633\u0627\u0639\u0629 \u0637\u0648\u0627\u0644 \u0623\u064a\u0627\u0645 \u0627\u0644\u0623\u0633\u0628\u0648\u0639 \u0644\u0644\u062a\u062f\u062e\u0644\u0627\u062a \u0627\u0644\u0639\u0627\u062c\u0644\u0629.<\/li>\n\n\n\n<li><strong>\u062a\u0634\u063a\u064a\u0644 \u062e\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0648\u062a\u0639\u062f\u064a\u0644\u0627\u062a\u0647:<\/strong>\u00a0\u062f\u0639\u0645 \u0645\u0634\u0627\u0631\u064a\u0639 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621 \u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0639\u0627\u0644\u0645.<\/li>\n\n\n\n<li><strong>\u062d\u0644\u0648\u0644 \u0627\u0644\u0635\u064a\u0627\u0646\u0629 \u0627\u0644\u0648\u0642\u0627\u0626\u064a\u0629 \u0648\u0627\u0644\u0646\u0632\u0627\u0647\u0629:<\/strong>\u00a0\u062a\u0645\u062f\u064a\u062f \u062f\u0648\u0631\u0627\u062a \u062d\u064a\u0627\u0629 \u0627\u0644\u0623\u0635\u0648\u0644.<\/li>\n<\/ul>\n\n\n\n<p><strong>\u0646\u062d\u0646 \u0646\u062c\u0645\u0639 \u0628\u064a\u0646 \u0627\u0644\u062a\u0641\u0648\u0642 \u0627\u0644\u0647\u0646\u062f\u0633\u064a \u0648\u0627\u0644\u062e\u0628\u0631\u0629 \u0627\u0644\u0645\u064a\u062f\u0627\u0646\u064a\u0629 \u0627\u0644\u0645\u062b\u0628\u062a\u0629 \u0644\u062a\u0642\u062f\u064a\u0645 \u062d\u0644\u0648\u0644 \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0622\u0645\u0646\u0629 \u0648\u0641\u0639\u0627\u0644\u0629 \u0648\u0645\u062a\u0641\u0648\u0642\u0629 \u0627\u0642\u062a\u0635\u0627\u062f\u064a\u064b\u0627.<\/strong><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Project Snapshot: Category Details Client International Energy Major (EPC Project) Location Ningbo, China Core Challenge Execute 12\u00a0hot taps\u00a0on\u00a0live, high-pressure (7.0 MPa) natural gas\u00a0and\u00a0high-temperature (300\u00b0C) thermal oil\u00a0pipelines made of\u00a0high-grade steel (X60\/L415Q)\u00a0with\u00a0thick, non-standard walls,\u00a0without shutdown. JSW Solution Custom-engineered\u00a0hot tapping services, including design\/fabrication of heavy-duty fittings, stringent welding procedures, and deployment of proprietary\u00a0high-capacity drilling equipment. A full-scope\u00a0EPC support [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[314,316,313,318,75,29,317,315],"class_list":["post-4513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projects","tag-epc-pipeline-services","tag-high-pressure-hot-tapping-contractor","tag-hot-tap-services","tag-jsw-pipeline-company","tag-jsw-projects","tag-pipeline-hot-tapping","tag-pipeline-modification-services","tag-under-pressure-drilling"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>High-Pressure, High-Temperature Hot Tapping on X60 &amp; L415Q Pipelines: A Critical EPC Case Study at Ningbo Terminal | JSW Pipeline Services<\/title>\n<meta name=\"description\" content=\"See how JSW Pipeline Services, as the specialist contractor, executed complex pipeline hot tapping and under pressure drilling services on 300\u00b0C thermal oil &amp; 7.0MPa gas lines for a major LNG terminal expansion. Our EPC pipeline services ensured zero shutdowns.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pipetechservice.com\/ar\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Full Record of High-Pressure, High-Temperature Hot Tapping for the Ningbo LNG Terminal EPC Project\u00a0\" \/>\n<meta property=\"og:description\" content=\"See how JSW Pipeline Services, as the specialist contractor, executed complex pipeline hot tapping and under pressure drilling services on 300\u00b0C thermal oil &amp; 7.0MPa gas lines for a major LNG terminal expansion. Our EPC pipeline services ensured zero shutdowns.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pipetechservice.com\/ar\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/\" \/>\n<meta property=\"og:site_name\" content=\"JSW Pipeline Service\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-02T01:08:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T01:39:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"570\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jasonsong889@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jasonsong889@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/\"},\"author\":{\"name\":\"jasonsong889@gmail.com\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/person\\\/c2f337d45f7612353b91c42331c72259\"},\"headline\":\"A Full Record of High-Pressure, High-Temperature Hot Tapping for the Ningbo LNG Terminal EPC Project\u00a0\",\"datePublished\":\"2026-01-02T01:08:38+00:00\",\"dateModified\":\"2026-06-20T01:39:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/\"},\"wordCount\":909,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg\",\"keywords\":[\"EPC pipeline services\",\"high pressure hot tapping contractor\",\"hot tap services\",\"JSW Pipeline Company\",\"JSW Projects\",\"Pipeline hot tapping\",\"pipeline modification services\",\"under pressure drilling\"],\"articleSection\":[\"Projects\"],\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/\",\"name\":\"High-Pressure, High-Temperature Hot Tapping on X60 & L415Q Pipelines: A Critical EPC Case Study at Ningbo Terminal | JSW Pipeline Services\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg\",\"datePublished\":\"2026-01-02T01:08:38+00:00\",\"dateModified\":\"2026-06-20T01:39:07+00:00\",\"description\":\"See how JSW Pipeline Services, as the specialist contractor, executed complex pipeline hot tapping and under pressure drilling services on 300\u00b0C thermal oil & 7.0MPa gas lines for a major LNG terminal expansion. Our EPC pipeline services ensured zero shutdowns.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg\",\"width\":570,\"height\":360,\"caption\":\"Pipeline (with elbow) connected to hot tapping equipment, with scaffolding and crane ready for under pressure drilling in EPC project\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pipetechservice.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Full Record of High-Pressure, High-Temperature Hot Tapping for the Ningbo LNG Terminal EPC Project\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/\",\"name\":\"JSW Pipeline Service\",\"description\":\"Building It Better In Concrete\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pipetechservice.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\",\"name\":\"Beijing Jinshiwan Pipeline Technology Co., Ltd.\",\"alternateName\":\"JSW\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"width\":996,\"height\":296,\"caption\":\"Beijing Jinshiwan Pipeline Technology Co., Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/person\\\/c2f337d45f7612353b91c42331c72259\",\"name\":\"jasonsong889@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"caption\":\"jasonsong889@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/www.pipetechservice.com\"],\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/ar\\\/author\\\/jasonsong889gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0639\u0627\u0644\u064a \u0627\u0644\u0636\u063a\u0637 \u0648\u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u0639\u0627\u0644\u064a\u0629 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 X60 \u0648 L415Q: \u062f\u0631\u0627\u0633\u0629 \u062d\u0627\u0644\u0629 \u062d\u0631\u062c\u0629 \u0644\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621 \u0641\u064a \u0645\u062d\u0637\u0629 \u0646\u064a\u0646\u063a\u0628\u0648 | JSW \u0644\u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628","description":"\u0634\u0627\u0647\u062f \u0643\u064a\u0641 \u0642\u0627\u0645\u062a \u0634\u0631\u0643\u0629 JSW \u0644\u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628\u060c \u0628\u0635\u0641\u062a\u0647\u0627 \u0627\u0644\u0645\u0642\u0627\u0648\u0644 \u0627\u0644\u0645\u062a\u062e\u0635\u0635\u060c \u0628\u062a\u0646\u0641\u064a\u0630 \u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062d\u0641\u0631 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0645\u0639\u0642\u062f\u0629 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0627\u0644\u0646\u0641\u0637 \u0627\u0644\u062d\u0631\u0627\u0631\u064a \u0628\u062f\u0631\u062c\u0629 300 \u062f\u0631\u062c\u0629 \u0645\u0626\u0648\u064a\u0629 \u0648\u062e\u0637\u0648\u0637 \u0627\u0644\u063a\u0627\u0632 7.0 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644 \u0644\u062a\u0648\u0633\u0639\u0629 \u0645\u062d\u0637\u0629 \u0627\u0644\u063a\u0627\u0632 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0627\u0644\u0645\u0633\u0627\u0644 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629. \u0636\u0645\u0646\u062a \u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621 \u0644\u062f\u064a\u0646\u0627 \u0639\u062f\u0645 \u062d\u062f\u0648\u062b \u0623\u064a \u062a\u0648\u0642\u0641.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pipetechservice.com\/ar\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/","og_locale":"ar_AR","og_type":"article","og_title":"A Full Record of High-Pressure, High-Temperature Hot Tapping for the Ningbo LNG Terminal EPC Project\u00a0","og_description":"See how JSW Pipeline Services, as the specialist contractor, executed complex pipeline hot tapping and under pressure drilling services on 300\u00b0C thermal oil & 7.0MPa gas lines for a major LNG terminal expansion. Our EPC pipeline services ensured zero shutdowns.","og_url":"https:\/\/www.pipetechservice.com\/ar\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/","og_site_name":"JSW Pipeline Service","article_published_time":"2026-01-02T01:08:38+00:00","article_modified_time":"2026-06-20T01:39:07+00:00","og_image":[{"width":570,"height":360,"url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg","type":"image\/jpeg"}],"author":"jasonsong889@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jasonsong889@gmail.com","Est. reading time":"5 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#article","isPartOf":{"@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/"},"author":{"name":"jasonsong889@gmail.com","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/person\/c2f337d45f7612353b91c42331c72259"},"headline":"A Full Record of High-Pressure, High-Temperature Hot Tapping for the Ningbo LNG Terminal EPC Project\u00a0","datePublished":"2026-01-02T01:08:38+00:00","dateModified":"2026-06-20T01:39:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/"},"wordCount":909,"commentCount":0,"publisher":{"@id":"https:\/\/www.pipetechservice.com\/#organization"},"image":{"@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg","keywords":["EPC pipeline services","high pressure hot tapping contractor","hot tap services","JSW Pipeline Company","JSW Projects","Pipeline hot tapping","pipeline modification services","under pressure drilling"],"articleSection":["Projects"],"inLanguage":"ar","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/","url":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/","name":"\u0627\u0644\u062a\u0646\u0635\u062a \u0627\u0644\u0633\u0627\u062e\u0646 \u0639\u0627\u0644\u064a \u0627\u0644\u0636\u063a\u0637 \u0648\u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u0639\u0627\u0644\u064a\u0629 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 X60 \u0648 L415Q: \u062f\u0631\u0627\u0633\u0629 \u062d\u0627\u0644\u0629 \u062d\u0631\u062c\u0629 \u0644\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621 \u0641\u064a \u0645\u062d\u0637\u0629 \u0646\u064a\u0646\u063a\u0628\u0648 | JSW \u0644\u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628","isPartOf":{"@id":"https:\/\/www.pipetechservice.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#primaryimage"},"image":{"@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg","datePublished":"2026-01-02T01:08:38+00:00","dateModified":"2026-06-20T01:39:07+00:00","description":"\u0634\u0627\u0647\u062f \u0643\u064a\u0641 \u0642\u0627\u0645\u062a \u0634\u0631\u0643\u0629 JSW \u0644\u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628\u060c \u0628\u0635\u0641\u062a\u0647\u0627 \u0627\u0644\u0645\u0642\u0627\u0648\u0644 \u0627\u0644\u0645\u062a\u062e\u0635\u0635\u060c \u0628\u062a\u0646\u0641\u064a\u0630 \u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062d\u0641\u0631 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0627\u0644\u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0645\u0639\u0642\u062f\u0629 \u062a\u062d\u062a \u0627\u0644\u0636\u063a\u0637 \u0639\u0644\u0649 \u062e\u0637\u0648\u0637 \u0627\u0644\u0646\u0641\u0637 \u0627\u0644\u062d\u0631\u0627\u0631\u064a \u0628\u062f\u0631\u062c\u0629 300 \u062f\u0631\u062c\u0629 \u0645\u0626\u0648\u064a\u0629 \u0648\u062e\u0637\u0648\u0637 \u0627\u0644\u063a\u0627\u0632 7.0 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644 \u0644\u062a\u0648\u0633\u0639\u0629 \u0645\u062d\u0637\u0629 \u0627\u0644\u063a\u0627\u0632 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0627\u0644\u0645\u0633\u0627\u0644 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629. \u0636\u0645\u0646\u062a \u062e\u062f\u0645\u0627\u062a \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 \u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0648\u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a \u0648\u0627\u0644\u0628\u0646\u0627\u0621 \u0644\u062f\u064a\u0646\u0627 \u0639\u062f\u0645 \u062d\u062f\u0648\u062b \u0623\u064a \u062a\u0648\u0642\u0641.","breadcrumb":{"@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#primaryimage","url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg","contentUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg","width":570,"height":360,"caption":"Pipeline (with elbow) connected to hot tapping equipment, with scaffolding and crane ready for under pressure drilling in EPC project"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pipetechservice.com\/a-full-record-of-high-pressure-high-temperature-hot-tapping-for-the-ningbo-lng-terminal-epc-project\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pipetechservice.com\/"},{"@type":"ListItem","position":2,"name":"A Full Record of High-Pressure, High-Temperature Hot Tapping for the Ningbo LNG Terminal EPC Project\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.pipetechservice.com\/#website","url":"https:\/\/www.pipetechservice.com\/","name":"\u062e\u062f\u0645\u0629 \u062e\u0637\u0648\u0637 \u0623\u0646\u0627\u0628\u064a\u0628 JSW","description":"\u0627\u0644\u0628\u0646\u0627\u0621 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0641\u064a \u0627\u0644\u062e\u0631\u0633\u0627\u0646\u0629","publisher":{"@id":"https:\/\/www.pipetechservice.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pipetechservice.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.pipetechservice.com\/#organization","name":"Beijing Jinshiwan Pipeline Technology Co., Ltd.","alternateName":"JSW","url":"https:\/\/www.pipetechservice.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/07\/logo.jpg","contentUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/07\/logo.jpg","width":996,"height":296,"caption":"Beijing Jinshiwan Pipeline Technology Co., Ltd."},"image":{"@id":"https:\/\/www.pipetechservice.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/person\/c2f337d45f7612353b91c42331c72259","name":"jasonsong889@gmail.com","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","caption":"jasonsong889@gmail.com"},"sameAs":["https:\/\/www.pipetechservice.com"],"url":"https:\/\/www.pipetechservice.com\/ar\/author\/jasonsong889gmail-com\/"}]}},"spectra_custom_meta":{"_edit_lock":["1781919550:1"],"_surecart_dashboard_logo_width":["180px"],"_surecart_dashboard_show_logo":["1"],"_surecart_dashboard_navigation_orders":["1"],"_surecart_dashboard_navigation_invoices":["1"],"_surecart_dashboard_navigation_subscriptions":["1"],"_surecart_dashboard_navigation_downloads":["1"],"_surecart_dashboard_navigation_billing":["1"],"_surecart_dashboard_navigation_account":["1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_elementor_edit_mode":[""],"_elementor_template_type":[""],"_elementor_data":[""],"_elementor_conditions":["a:0:{}"],"_edit_last":["1"],"_yoast_wpseo_primary_category":["1"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_focuskeywords":[""],"_yoast_wpseo_keywordsynonyms":[""],"_yoast_wpseo_estimated-reading-time-minutes":["5"],"_thumbnail_id":["4516"],"_yoast_indexnow_last_ping":["1781919548"],"_yoast_wpseo_focuskw":["hot tap services"],"_yoast_wpseo_title":["High-Pressure, High-Temperature Hot Tapping on X60 & L415Q Pipelines: A Critical EPC Case Study at Ningbo Terminal | JSW Pipeline Services"],"_yoast_wpseo_metadesc":["See how JSW Pipeline Services, as the specialist contractor, executed complex pipeline hot tapping and under pressure drilling services on 300\u00b0C thermal oil & 7.0MPa gas lines for a major LNG terminal expansion. Our EPC pipeline services ensured zero shutdowns."],"_yoast_wpseo_linkdex":["58"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:6;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:4;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_yoast_wpseo_schema_page_type":["WebPage"],"_yoast_wpseo_schema_article_type":["TechArticle"],"_uag_css_file_name":["uag-css-4513.css"],"_elementor_page_assets":["a:0:{}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:52296:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-container.uagb-block-809ae73a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-809ae73a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-809ae73a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-809ae73a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-809ae73a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-809ae73a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-809ae73a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-809ae73a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a4135039 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a4135039 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a4135039 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a4135039 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a4135039 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a4135039{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a4135039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a4135039{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-366f3850.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-366f3850.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-366f3850.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-366f3850.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-366f3850.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-366f3850.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-366f3850.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-366f3850.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-b906b3d8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b906b3d8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b906b3d8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b906b3d8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b906b3d8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b906b3d8{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b906b3d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b906b3d8{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4fd1b156.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4fd1b156.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4fd1b156.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-4fd1b156.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4fd1b156.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4fd1b156.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-49c0b3bf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-49c0b3bf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-49c0b3bf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-49c0b3bf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-49c0b3bf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49c0b3bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49c0b3bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-49c0b3bf{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-924f037b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-924f037b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-924f037b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-924f037b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-924f037b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-924f037b{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-924f037b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-924f037b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f0da1dd9.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-f0da1dd9.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-f0da1dd9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-f0da1dd9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-f0da1dd9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f0da1dd9.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-a33e4dbc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a33e4dbc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a33e4dbc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a33e4dbc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a33e4dbc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a33e4dbc{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a33e4dbc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a33e4dbc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cd9032eb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-cd9032eb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-cd9032eb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-cd9032eb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-cd9032eb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cd9032eb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-809ae73a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-809ae73a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-809ae73a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a4135039{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a4135039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a4135039{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-366f3850.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b906b3d8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b906b3d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b906b3d8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-4fd1b156.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49c0b3bf{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49c0b3bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-49c0b3bf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-924f037b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-924f037b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-924f037b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-f0da1dd9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a33e4dbc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a33e4dbc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a33e4dbc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-cd9032eb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-809ae73a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-809ae73a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-809ae73a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a4135039{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a4135039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a4135039{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-366f3850.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b906b3d8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b906b3d8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b906b3d8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-4fd1b156.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-49c0b3bf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-49c0b3bf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-49c0b3bf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-924f037b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-924f037b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-924f037b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-f0da1dd9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a33e4dbc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a33e4dbc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a33e4dbc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-cd9032eb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16 .uagb-heading-text{font-size: 22px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37 .uagb-heading-text{font-size: 22px;margin-bottom: 15px;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-ab31a061.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ab31a061.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d17e4438.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d17e4438.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ca14edc7.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ca14edc7.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-wrap{margin-right: 15px;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:46:{i:0;s:12:\"core\/heading\";i:1;s:10:\"core\/table\";i:2;s:14:\"core\/paragraph\";i:3;s:9:\"core\/list\";i:4;s:14:\"core\/list-item\";i:5;s:14:\"uagb\/container\";i:7;s:10:\"uagb\/image\";i:8;s:23:\"surecart\/slide-out-cart\";i:9;s:10:\"core\/group\";i:10;s:26:\"surecart\/cart-close-button\";i:11;s:19:\"surecart\/cart-count\";i:13;s:34:\"surecart\/slide-out-cart-line-items\";i:16;s:29:\"surecart\/cart-line-item-image\";i:20;s:29:\"surecart\/cart-line-item-title\";i:22;s:34:\"surecart\/cart-line-item-price-name\";i:23;s:31:\"surecart\/cart-line-item-variant\";i:24;s:28:\"surecart\/cart-line-item-note\";i:25;s:30:\"surecart\/cart-line-item-status\";i:28;s:38:\"surecart\/cart-line-item-scratch-amount\";i:29;s:30:\"surecart\/cart-line-item-amount\";i:30;s:32:\"surecart\/cart-line-item-interval\";i:32;s:29:\"surecart\/cart-line-item-trial\";i:33;s:28:\"surecart\/cart-line-item-fees\";i:36;s:32:\"surecart\/cart-line-item-quantity\";i:38;s:30:\"surecart\/cart-line-item-remove\";i:40;s:25:\"surecart\/cart-order-bumps\";i:41;s:35:\"surecart\/cart-order-bump-pagination\";i:42;s:44:\"surecart\/cart-order-bump-pagination-previous\";i:43;s:40:\"surecart\/cart-order-bump-pagination-next\";i:44;s:33:\"surecart\/cart-order-bump-template\";i:46;s:30:\"surecart\/cart-order-bump-image\";i:48;s:30:\"surecart\/cart-order-bump-title\";i:49;s:36:\"surecart\/cart-order-bump-description\";i:51;s:39:\"surecart\/cart-order-bump-scratch-amount\";i:52;s:31:\"surecart\/cart-order-bump-amount\";i:53;s:35:\"surecart\/cart-order-bump-add-button\";i:55;s:38:\"surecart\/slide-out-cart-items-subtotal\";i:57;s:37:\"surecart\/cart-subtotal-scratch-amount\";i:58;s:29:\"surecart\/cart-subtotal-amount\";i:59;s:36:\"surecart\/slide-out-cart-items-submit\";i:60;s:11:\"core\/search\";i:61;s:17:\"core\/latest-posts\";i:62;s:30:\"woocommerce\/product-categories\";i:63;s:21:\"uagb\/advanced-heading\";i:64;s:14:\"uagb\/icon-list\";i:65;s:20:\"uagb\/icon-list-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1783850060\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg",570,360,false],"thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project-150x150.jpg",150,150,true],"medium":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project-300x189.jpg",300,189,true],"medium_large":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg",570,360,false],"large":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg",570,360,false],"1536x1536":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg",570,360,false],"2048x2048":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg",570,360,false],"trp-custom-language-flag":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg",18,12,false],"woocommerce_thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project.jpg",570,360,false],"woocommerce_gallery_thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2026\/01\/Preparation-for-Pipeline-Hot-Tapping-in-EPC-Pipeline-Modification-Project-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"jasonsong889@gmail.com","author_link":"https:\/\/www.pipetechservice.com\/ar\/author\/jasonsong889gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Project Snapshot: Category Details Client International Energy Major (EPC Project) Location Ningbo, China Core Challenge Execute 12\u00a0hot taps\u00a0on\u00a0live, high-pressure (7.0 MPa) natural gas\u00a0and\u00a0high-temperature (300\u00b0C) thermal oil\u00a0pipelines made of\u00a0high-grade steel (X60\/L415Q)\u00a0with\u00a0thick, non-standard walls,\u00a0without shutdown. JSW Solution Custom-engineered\u00a0hot tapping services, including design\/fabrication of heavy-duty fittings, stringent welding procedures, and deployment of proprietary\u00a0high-capacity drilling equipment. A full-scope\u00a0EPC support&hellip;","_links":{"self":[{"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/posts\/4513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/comments?post=4513"}],"version-history":[{"count":5,"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/posts\/4513\/revisions"}],"predecessor-version":[{"id":4523,"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/posts\/4513\/revisions\/4523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/media\/4516"}],"wp:attachment":[{"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/media?parent=4513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/categories?post=4513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ar\/wp-json\/wp\/v2\/tags?post=4513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}