{"id":3267,"date":"2025-08-10T02:51:46","date_gmt":"2025-08-10T02:51:46","guid":{"rendered":"https:\/\/www.pipetechservice.com\/?p=3267"},"modified":"2026-06-20T02:01:12","modified_gmt":"2026-06-20T02:01:12","slug":"north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed","status":"publish","type":"post","link":"https:\/\/www.pipetechservice.com\/es\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/","title":{"rendered":"Finaliza con \u00e9xito el proyecto de rescate de emergencia del oleoducto 219 del yacimiento petrol\u00edfero del norte de China"},"content":{"rendered":"<p>Recientemente, las persistentes lluvias torrenciales en el norte de China provocaron inundaciones y desastres geol\u00f3gicos en Pek\u00edn, Tianjin y Hebei. Un oleoducto cr\u00edtico DN200 de North China Oilfield en Wen'an, Langfang, corr\u00eda grave peligro. Si la inundaci\u00f3n hubiera roto el oleoducto, provocando un vertido de crudo, no s\u00f3lo habr\u00eda interrumpido la producci\u00f3n, sino que habr\u00eda agravado la cat\u00e1strofe, provocando consecuencias impensables.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d6234613 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-uagb-container uagb-block-2ff4b83a\">\n<div class=\"wp-block-uagb-image uagb-block-a7643eeb wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-3.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-3.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-3.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-3.jpg\" alt=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China del Norte\" class=\"uag-image-3270\" width=\"800\" height=\"600\" title=\"Proyecto de reparaci\u00f3n de emergencia del oleoducto 219 de China Septentrional-3\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-65b3e339 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-4.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-4.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-4.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-4.jpg\" alt=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China del Norte\" class=\"uag-image-3271\" width=\"800\" height=\"600\" title=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China del Norte-4\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p>Tras mantener conversaciones de emergencia, la unidad de gesti\u00f3n del crudo decidi\u00f3 instalar dos v\u00e1lvulas de cierre de emergencia adicionales a lo largo del oleoducto. Estas v\u00e1lvulas permitir\u00edan el aislamiento inmediato en caso de rotura, minimizando las fugas y manteniendo al mismo tiempo el funcionamiento normal del sistema. Tras recibir la orden de rescate, nuestra empresa activ\u00f3 los protocolos de emergencia durante la noche. El director del proyecto, Chen Hao, organiz\u00f3 una sesi\u00f3n informativa t\u00e9cnica antes de dirigir r\u00e1pidamente al equipo de ingenieros al lugar. Mientras tanto, los supervisores de obra, Yao Yuanjun y Lu Shaoliang, fueron designados para supervisar las operaciones in situ.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f2e8fc69 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-uagb-image uagb-block-90406ccb wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-6.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-6.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-6.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-6.jpg\" alt=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China del Norte\" class=\"uag-image-3273\" width=\"800\" height=\"600\" title=\"Proyecto de Reparaci\u00f3n de Urgencia del Oleoducto 219 de China Septentrional-6\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-91d8efb4\">\n<div class=\"wp-block-uagb-image uagb-block-175dfaf9 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-7.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-7.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-7.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-7.jpg\" alt=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China del Norte\" class=\"uag-image-3274\" width=\"800\" height=\"600\" title=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China Septentrional-7\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p>En&nbsp;<strong>22:06 el 26 de julio de 2025<\/strong>, un cami\u00f3n de 6,8 metros cargado con suministros de emergencia corri\u00f3 a trav\u00e9s de la tormentosa noche hacia Wen'an. En&nbsp;<strong>11:04 PM<\/strong>, le sigui\u00f3 un segundo cami\u00f3n, y por&nbsp;<strong>12:14 AM<\/strong>, un cami\u00f3n de 9,6 metros se uni\u00f3 al convoy de refuerzos que converg\u00eda en la zona de crisis. A su llegada, el trabajo comenz\u00f3 de inmediato. En&nbsp;<strong>3:04 AM on Julio 27<\/strong>, La excavaci\u00f3n de la fosa de explotaci\u00f3n se complet\u00f3, seguida del refuerzo del talud. En&nbsp;<strong>4:27 AM<\/strong>, Los equipos de soldadura se reunieron y comenzaron a instalar las juntas en T, cada paso ejecutado con precisi\u00f3n bajo una inmensa presi\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c26c2729 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-uagb-image uagb-block-7164e93f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-8.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-8.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-8.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-8.jpg\" alt=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China del Norte\" class=\"uag-image-3275\" width=\"800\" height=\"600\" title=\"Proyecto de reparaci\u00f3n urgente del oleoducto 219 de China del Norte-8\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p>El reto m\u00e1s angustioso fue un tramo bajo amenazado por las aguas y la lluvia incesante. A pesar de los caminos embarrados, los veh\u00edculos atascados y las obras nocturnas, el equipo persever\u00f3 y demostr\u00f3 una determinaci\u00f3n inquebrantable.<\/p>\n\n\n\n<p>En&nbsp;<strong>tres d\u00edas y tres noches de incansable esfuerzo<\/strong>, el avance se produjo en&nbsp;<strong>20:20 del 29 de julio<\/strong>-se completaron el sellado y la instalaci\u00f3n aguas abajo, lo que supuso toda una victoria. El proyecto elimin\u00f3 los riesgos para la unidad de gesti\u00f3n de crudo y prest\u00f3 un apoyo fundamental a la respuesta a las inundaciones de la Nueva Zona de Xiongan, lo que mereci\u00f3 el elogio un\u00e1nime de las partes interesadas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Recently, persistent heavy rainfall in North China triggered floods and geological disasters across Beijing, Tianjin, and Hebei. A critical DN200 crude oil pipeline operated by North China Oilfield in Wen&#8217;an, Langfang, was at severe risk. Had the flood ruptured the pipeline, causing a crude oil spill, it would have not only disrupted production but also [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[74,1],"tags":[75],"class_list":["post-3267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-projects","tag-jsw-projects"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed! - JSW Pipeline Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pipetechservice.com\/es\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed!\" \/>\n<meta property=\"og:description\" content=\"Recently, persistent heavy rainfall in North China triggered floods and geological disasters across Beijing, Tianjin, and Hebei. A critical DN200 crude oil pipeline operated by North China Oilfield in Wen&#8217;an, Langfang, was at severe risk. Had the flood ruptured the pipeline, causing a crude oil spill, it would have not only disrupted production but also [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pipetechservice.com\/es\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/\" \/>\n<meta property=\"og:site_name\" content=\"JSW Pipeline Service\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-10T02:51:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T02:01:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"570\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jasonsong889@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jasonsong889@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/\"},\"author\":{\"name\":\"jasonsong889@gmail.com\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/person\\\/c2f337d45f7612353b91c42331c72259\"},\"headline\":\"North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed!\",\"datePublished\":\"2025-08-10T02:51:46+00:00\",\"dateModified\":\"2026-06-20T02:01:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg\",\"keywords\":[\"JSW Projects\"],\"articleSection\":[\"News\",\"Projects\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/\",\"name\":\"North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed! - JSW Pipeline Service\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg\",\"datePublished\":\"2025-08-10T02:51:46+00:00\",\"dateModified\":\"2026-06-20T02:01:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg\",\"width\":570,\"height\":360,\"caption\":\"North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pipetechservice.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/\",\"name\":\"JSW Pipeline Service\",\"description\":\"Building It Better In Concrete\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pipetechservice.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\",\"name\":\"Beijing Jinshiwan Pipeline Technology Co., Ltd.\",\"alternateName\":\"JSW\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"width\":996,\"height\":296,\"caption\":\"Beijing Jinshiwan Pipeline Technology Co., Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/person\\\/c2f337d45f7612353b91c42331c72259\",\"name\":\"jasonsong889@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"caption\":\"jasonsong889@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/www.pipetechservice.com\"],\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/es\\\/author\\\/jasonsong889gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finaliza con \u00e9xito el proyecto de rescate de emergencia del oleoducto 219 del yacimiento petrol\u00edfero del norte de China - JSW Pipeline Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pipetechservice.com\/es\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/","og_locale":"es_ES","og_type":"article","og_title":"North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed!","og_description":"Recently, persistent heavy rainfall in North China triggered floods and geological disasters across Beijing, Tianjin, and Hebei. A critical DN200 crude oil pipeline operated by North China Oilfield in Wen&#8217;an, Langfang, was at severe risk. Had the flood ruptured the pipeline, causing a crude oil spill, it would have not only disrupted production but also [&hellip;]","og_url":"https:\/\/www.pipetechservice.com\/es\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/","og_site_name":"JSW Pipeline Service","article_published_time":"2025-08-10T02:51:46+00:00","article_modified_time":"2026-06-20T02:01:12+00:00","og_image":[{"width":570,"height":360,"url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg","type":"image\/jpeg"}],"author":"jasonsong889@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jasonsong889@gmail.com","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#article","isPartOf":{"@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/"},"author":{"name":"jasonsong889@gmail.com","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/person\/c2f337d45f7612353b91c42331c72259"},"headline":"North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed!","datePublished":"2025-08-10T02:51:46+00:00","dateModified":"2026-06-20T02:01:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/www.pipetechservice.com\/#organization"},"image":{"@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg","keywords":["JSW Projects"],"articleSection":["News","Projects"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/","url":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/","name":"Finaliza con \u00e9xito el proyecto de rescate de emergencia del oleoducto 219 del yacimiento petrol\u00edfero del norte de China - JSW Pipeline Service","isPartOf":{"@id":"https:\/\/www.pipetechservice.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#primaryimage"},"image":{"@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg","datePublished":"2025-08-10T02:51:46+00:00","dateModified":"2026-06-20T02:01:12+00:00","breadcrumb":{"@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#primaryimage","url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg","contentUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg","width":570,"height":360,"caption":"North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pipetechservice.com\/north-china-oilfield-pipeline-219-emergency-rescue-project-successfully-completed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pipetechservice.com\/"},{"@type":"ListItem","position":2,"name":"North China Oilfield Pipeline 219 Emergency Rescue Project Successfully Completed!"}]},{"@type":"WebSite","@id":"https:\/\/www.pipetechservice.com\/#website","url":"https:\/\/www.pipetechservice.com\/","name":"JSW Pipeline Service","description":"Construir mejor en hormig\u00f3n","publisher":{"@id":"https:\/\/www.pipetechservice.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pipetechservice.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pipetechservice.com\/#organization","name":"Beijing Jinshiwan Pipeline Technology Co., Ltd.","alternateName":"JSW","url":"https:\/\/www.pipetechservice.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/07\/logo.jpg","contentUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/07\/logo.jpg","width":996,"height":296,"caption":"Beijing Jinshiwan Pipeline Technology Co., Ltd."},"image":{"@id":"https:\/\/www.pipetechservice.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/person\/c2f337d45f7612353b91c42331c72259","name":"jasonsong889@gmail.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","caption":"jasonsong889@gmail.com"},"sameAs":["https:\/\/www.pipetechservice.com"],"url":"https:\/\/www.pipetechservice.com\/es\/author\/jasonsong889gmail-com\/"}]}},"spectra_custom_meta":{"_edit_lock":["1781920878:1"],"_thumbnail_id":["3285"],"_surecart_dashboard_logo_width":["180px"],"_surecart_dashboard_show_logo":["1"],"_surecart_dashboard_navigation_orders":["1"],"_surecart_dashboard_navigation_invoices":["1"],"_surecart_dashboard_navigation_subscriptions":["1"],"_surecart_dashboard_navigation_downloads":["1"],"_surecart_dashboard_navigation_billing":["1"],"_surecart_dashboard_navigation_account":["1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_elementor_edit_mode":[""],"_elementor_template_type":[""],"_elementor_data":[""],"_elementor_conditions":["a:0:{}"],"_edit_last":["1"],"_yoast_indexnow_last_ping":["1781920872"],"_yoast_wpseo_primary_category":["1"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_focuskeywords":[""],"_yoast_wpseo_keywordsynonyms":[""],"_yoast_wpseo_estimated-reading-time-minutes":["3"],"_wp_page_template":["default"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:5;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:5;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_yoast_wpseo_schema_page_type":["WebPage"],"_yoast_wpseo_schema_article_type":["TechArticle"],"_uag_css_file_name":["uag-css-3267.css"],"_elementor_page_assets":["a:0:{}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:51931:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-container.uagb-block-d6234613 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d6234613 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d6234613 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d6234613 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d6234613 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d6234613{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d6234613 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d6234613{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2ff4b83a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ff4b83a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ff4b83a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ff4b83a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ff4b83a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ff4b83a{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ff4b83a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2ff4b83a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a7643eeb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a7643eeb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a7643eeb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-a7643eeb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a7643eeb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a7643eeb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-65b3e339.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-65b3e339.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-65b3e339.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-65b3e339.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-65b3e339.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-65b3e339.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-65b3e339.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-65b3e339.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-f2e8fc69 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2e8fc69 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2e8fc69 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2e8fc69 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2e8fc69 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2e8fc69{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2e8fc69 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f2e8fc69{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-90406ccb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-90406ccb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-90406ccb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-90406ccb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-90406ccb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-90406ccb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-90406ccb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-90406ccb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-91d8efb4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-91d8efb4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-91d8efb4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-91d8efb4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-91d8efb4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-91d8efb4{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-91d8efb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-91d8efb4{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-175dfaf9.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-175dfaf9.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-175dfaf9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-175dfaf9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-175dfaf9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-175dfaf9.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-c26c2729 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c26c2729 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c26c2729 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c26c2729 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c26c2729 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c26c2729{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c26c2729 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c26c2729{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-7164e93f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7164e93f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-7164e93f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-7164e93f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-7164e93f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-7164e93f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-7164e93f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7164e93f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d6234613{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d6234613 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d6234613{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ff4b83a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ff4b83a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2ff4b83a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-a7643eeb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-65b3e339.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2e8fc69{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2e8fc69 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f2e8fc69{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-90406ccb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-91d8efb4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-91d8efb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-91d8efb4{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-175dfaf9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c26c2729{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c26c2729 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c26c2729{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-7164e93f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d6234613{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d6234613 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d6234613{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ff4b83a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ff4b83a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2ff4b83a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-a7643eeb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-65b3e339.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2e8fc69{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2e8fc69 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f2e8fc69{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-90406ccb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-91d8efb4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-91d8efb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-91d8efb4{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-175dfaf9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c26c2729{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c26c2729 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c26c2729{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-7164e93f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16 .uagb-heading-text{font-size: 22px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37 .uagb-heading-text{font-size: 22px;margin-bottom: 15px;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-ab31a061.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ab31a061.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d17e4438.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d17e4438.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ca14edc7.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ca14edc7.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-wrap{margin-right: 15px;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:45:{i:0;s:14:\"core\/paragraph\";i:1;s:14:\"uagb\/container\";i:2;s:10:\"core\/group\";i:4;s:10:\"uagb\/image\";i:5;s:23:\"surecart\/slide-out-cart\";i:7;s:26:\"surecart\/cart-close-button\";i:8;s:19:\"surecart\/cart-count\";i:10;s:34:\"surecart\/slide-out-cart-line-items\";i:13;s:29:\"surecart\/cart-line-item-image\";i:17;s:29:\"surecart\/cart-line-item-title\";i:19;s:34:\"surecart\/cart-line-item-price-name\";i:20;s:31:\"surecart\/cart-line-item-variant\";i:21;s:28:\"surecart\/cart-line-item-note\";i:22;s:30:\"surecart\/cart-line-item-status\";i:25;s:38:\"surecart\/cart-line-item-scratch-amount\";i:26;s:30:\"surecart\/cart-line-item-amount\";i:27;s:32:\"surecart\/cart-line-item-interval\";i:29;s:29:\"surecart\/cart-line-item-trial\";i:30;s:28:\"surecart\/cart-line-item-fees\";i:33;s:32:\"surecart\/cart-line-item-quantity\";i:35;s:30:\"surecart\/cart-line-item-remove\";i:37;s:25:\"surecart\/cart-order-bumps\";i:38;s:35:\"surecart\/cart-order-bump-pagination\";i:39;s:44:\"surecart\/cart-order-bump-pagination-previous\";i:40;s:40:\"surecart\/cart-order-bump-pagination-next\";i:41;s:33:\"surecart\/cart-order-bump-template\";i:43;s:30:\"surecart\/cart-order-bump-image\";i:45;s:30:\"surecart\/cart-order-bump-title\";i:46;s:36:\"surecart\/cart-order-bump-description\";i:48;s:39:\"surecart\/cart-order-bump-scratch-amount\";i:49;s:31:\"surecart\/cart-order-bump-amount\";i:50;s:35:\"surecart\/cart-order-bump-add-button\";i:52;s:38:\"surecart\/slide-out-cart-items-subtotal\";i:54;s:37:\"surecart\/cart-subtotal-scratch-amount\";i:55;s:29:\"surecart\/cart-subtotal-amount\";i:56;s:36:\"surecart\/slide-out-cart-items-submit\";i:57;s:11:\"core\/search\";i:59;s:12:\"core\/heading\";i:60;s:17:\"core\/latest-posts\";i:61;s:30:\"woocommerce\/product-categories\";i:62;s:9:\"core\/list\";i:63;s:14:\"core\/list-item\";i:64;s:21:\"uagb\/advanced-heading\";i:65;s:14:\"uagb\/icon-list\";i:66;s:20:\"uagb\/icon-list-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1783850060\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg",570,360,false],"thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1-150x150.jpg",150,150,true],"medium":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1-300x189.jpg",300,189,true],"medium_large":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg",570,360,false],"large":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg",570,360,false],"1536x1536":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg",570,360,false],"2048x2048":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg",570,360,false],"trp-custom-language-flag":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg",18,12,false],"woocommerce_thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1.jpg",570,360,false],"woocommerce_gallery_thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/North-China-Oilfield-Pipeline-219-Emergency-Repair-Project-2-1-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"jasonsong889@gmail.com","author_link":"https:\/\/www.pipetechservice.com\/es\/author\/jasonsong889gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Recently, persistent heavy rainfall in North China triggered floods and geological disasters across Beijing, Tianjin, and Hebei. A critical DN200 crude oil pipeline operated by North China Oilfield in Wen&#8217;an, Langfang, was at severe risk. Had the flood ruptured the pipeline, causing a crude oil spill, it would have not only disrupted production but also&hellip;","_links":{"self":[{"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/posts\/3267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/comments?post=3267"}],"version-history":[{"count":1,"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/posts\/3267\/revisions"}],"predecessor-version":[{"id":3276,"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/posts\/3267\/revisions\/3276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/media\/3285"}],"wp:attachment":[{"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/media?parent=3267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/categories?post=3267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pipetechservice.com\/es\/wp-json\/wp\/v2\/tags?post=3267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}