{"id":3328,"date":"2025-08-10T05:50:49","date_gmt":"2025-08-10T05:50:49","guid":{"rendered":"https:\/\/www.pipetechservice.com\/?p=3328"},"modified":"2026-06-20T01:59:47","modified_gmt":"2026-06-20T01:59:47","slug":"jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo","status":"publish","type":"post","link":"https:\/\/www.pipetechservice.com\/ru\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/","title":{"rendered":"JSW \u0437\u0430\u0432\u043e\u0435\u0432\u0430\u043b\u0430 \u043c\u0438\u0440\u043e\u0432\u043e\u0435 \u043f\u0440\u0438\u0437\u043d\u0430\u043d\u0438\u0435 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u0442\u0435\u0445\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u043c \u0437\u043d\u0430\u043d\u0438\u044f\u043c \u043d\u0430 \u0443\u0441\u043f\u0435\u0448\u043d\u043e \u0437\u0430\u0432\u0435\u0440\u0448\u0438\u0432\u0448\u0435\u0439\u0441\u044f \u0432 2025 \u0433\u043e\u0434\u0443 \u041f\u0435\u043a\u0438\u043d\u0441\u043a\u043e\u0439 \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u0439 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0435 \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432!"},"content":{"rendered":"<p>8-\u044f \u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0438\u044f \u043f\u043e \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u0430\u043c (CIPC) \u0438 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430 \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u043e\u0433\u043e \u043e\u0431\u043e\u0440\u0443\u0434\u043e\u0432\u0430\u043d\u0438\u044f \u0443\u0441\u043f\u0435\u0448\u043d\u043e \u0437\u0430\u0432\u0435\u0440\u0448\u0438\u043b\u0438\u0441\u044c. \u041d\u0430 \u044d\u0442\u043e\u043c \u0433\u0440\u0430\u043d\u0434\u0438\u043e\u0437\u043d\u043e\u043c \u0441\u043e\u0431\u0440\u0430\u043d\u0438\u0438 \u044d\u043b\u0438\u0442\u044b \u043e\u0442\u0440\u0430\u0441\u043b\u0438 \u0438 \u043f\u0435\u0440\u0435\u0434\u043e\u0432\u044b\u0445 \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u0439 \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f Beijing Jinshiwan Pipeline Technology Co., Ltd. \u043f\u0440\u0438\u0432\u043b\u0435\u043a\u043b\u0430 \u043c\u043d\u043e\u0436\u0435\u0441\u0442\u0432\u043e \u043e\u0442\u0435\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0445 \u0438 \u0437\u0430\u0440\u0443\u0431\u0435\u0436\u043d\u044b\u0445 \u043a\u043b\u0438\u0435\u043d\u0442\u043e\u0432 \u043a \u0441\u0432\u043e\u0435\u043c\u0443 \u0441\u0442\u0435\u043d\u0434\u0443 \u0434\u043b\u044f \u043f\u043e\u0434\u0440\u043e\u0431\u043d\u044b\u0445 \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u0446\u0438\u0439.<\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-c8f13927 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-3.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-3.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-3.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-3.jpg\" alt=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-3\" class=\"uag-image-3332\" width=\"800\" height=\"600\" title=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-3\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p>\u042f\u0432\u043b\u044f\u044f\u0441\u044c \u0432\u044b\u0441\u043e\u043a\u043e\u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u0447\u043d\u044b\u043c \u043f\u0440\u0435\u0434\u043f\u0440\u0438\u044f\u0442\u0438\u0435\u043c, \u0441\u043f\u0435\u0446\u0438\u0430\u043b\u0438\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u043c\u0441\u044f \u043d\u0430 \u043e\u0431\u0441\u043b\u0443\u0436\u0438\u0432\u0430\u043d\u0438\u0438 \u043d\u0435\u0444\u0442\u0435\u0433\u0430\u0437\u043e\u0432\u044b\u0445 \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0438 \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0438\u0438 \u0443\u0441\u043b\u0443\u0433 \u043f\u043e \u0430\u0432\u0430\u0440\u0438\u0439\u043d\u043e\u043c\u0443 \u0440\u0435\u043c\u043e\u043d\u0442\u0443, \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f Jinshiwan \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u0438\u043b\u0430 \u043d\u0430 \u041f\u0435\u043a\u0438\u043d\u0441\u043a\u043e\u0439 \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u0439 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0435 \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 2025 \u0433\u043e\u0434\u0430 \u0441\u0432\u043e\u0438 \u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0440\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0438 \u0438 \u0440\u0435\u0448\u0435\u043d\u0438\u044f \u043f\u043e \u0430\u0432\u0430\u0440\u0438\u0439\u043d\u043e\u043c\u0443 \u0440\u0435\u043c\u043e\u043d\u0442\u0443, \u043f\u0440\u043e\u0434\u0435\u043c\u043e\u043d\u0441\u0442\u0440\u0438\u0440\u043e\u0432\u0430\u0432 \u043c\u0438\u0440\u043e\u0432\u044b\u043c \u044d\u043a\u0441\u043f\u0435\u0440\u0442\u0430\u043c, \u043f\u0430\u0440\u0442\u043d\u0435\u0440\u0430\u043c \u0438 \u043a\u043b\u0438\u0435\u043d\u0442\u0430\u043c \u0438\u043d\u043d\u043e\u0432\u0430\u0446\u0438\u043e\u043d\u043d\u044b\u0435 \u0432\u043e\u0437\u043c\u043e\u0436\u043d\u043e\u0441\u0442\u0438 \u041a\u0438\u0442\u0430\u044f \u0432 \u043e\u0431\u043b\u0430\u0441\u0442\u0438 \u0432\u043e\u0441\u0441\u0442\u0430\u043d\u043e\u0432\u043b\u0435\u043d\u0438\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-uagb-image uagb-block-c3e59185 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-8.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-8.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-8.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-8.jpg\" alt=\"\u041a\u0438\u0442\u0430\u0439-\u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f-\u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f-\u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-8\" class=\"uag-image-3336\" width=\"800\" height=\"600\" title=\"\u041a\u0438\u0442\u0430\u0439-\u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f-\u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f-\u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-8\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-9a014ec6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-6.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-6.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-6.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-6.jpg\" alt=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-6\" class=\"uag-image-3335\" width=\"800\" height=\"600\" title=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-6\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<p>\u0412 \u0445\u043e\u0434\u0435 \u043c\u0435\u0440\u043e\u043f\u0440\u0438\u044f\u0442\u0438\u044f \u043c\u044b \u043f\u0440\u043e\u0432\u0435\u043b\u0438 \u0448\u0438\u0440\u043e\u043a\u0438\u0439 \u043e\u0431\u043c\u0435\u043d \u043c\u043d\u0435\u043d\u0438\u044f\u043c\u0438 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u043c\u0438 \u043f\u043e\u0441\u0435\u0442\u0438\u0442\u0435\u043b\u044f\u043c\u0438 \u0438 \u0441\u043f\u0435\u0446\u0438\u0430\u043b\u0438\u0441\u0442\u0430\u043c\u0438 \u0438\u0437 \u0415\u0432\u0440\u043e\u043f\u044b, \u0411\u043b\u0438\u0436\u043d\u0435\u0433\u043e \u0412\u043e\u0441\u0442\u043e\u043a\u0430, \u042e\u0433\u043e-\u0412\u043e\u0441\u0442\u043e\u0447\u043d\u043e\u0439 \u0410\u0437\u0438\u0438 \u0438 \u0434\u0440\u0443\u0433\u0438\u0445 \u0440\u0435\u0433\u0438\u043e\u043d\u043e\u0432. \u0411\u044b\u043b\u0438 \u043f\u0440\u043e\u0432\u0435\u0434\u0435\u043d\u044b \u043f\u043e\u0434\u0440\u043e\u0431\u043d\u044b\u0435 \u043f\u0440\u0435\u0437\u0435\u043d\u0442\u0430\u0446\u0438\u0438 \u043e \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u0445 \u043f\u0440\u0435\u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430\u0445 \u043d\u0430\u0448\u0438\u0445 \u0437\u0430\u043f\u0430\u0442\u0435\u043d\u0442\u043e\u0432\u0430\u043d\u043d\u044b\u0445 \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u0439, \u0441\u0446\u0435\u043d\u0430\u0440\u0438\u044f\u0445 \u043f\u0440\u0438\u043c\u0435\u043d\u0435\u043d\u0438\u044f \u0438 \u0443\u0441\u043f\u0435\u0448\u043d\u044b\u0445 \u043f\u0440\u0438\u043c\u0435\u0440\u0430\u0445. \u0417\u0430\u0440\u0443\u0431\u0435\u0436\u043d\u044b\u0435 \u043a\u043b\u0438\u0435\u043d\u0442\u044b \u043f\u0440\u043e\u044f\u0432\u0438\u043b\u0438 \u043e\u0441\u043e\u0431\u044b\u0439 \u0438\u043d\u0442\u0435\u0440\u0435\u0441 \u043a \u0432\u043e\u0437\u043c\u043e\u0436\u043d\u043e\u0441\u0442\u044f\u043c \u0431\u044b\u0441\u0442\u0440\u043e\u0433\u043e \u0440\u0435\u0430\u0433\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f \u0438 \u0438\u043d\u0434\u0438\u0432\u0438\u0434\u0443\u0430\u043b\u044c\u043d\u044b\u043c \u0440\u0435\u0448\u0435\u043d\u0438\u044f\u043c Jinshiwan, \u0430 \u043d\u0435\u0441\u043a\u043e\u043b\u044c\u043a\u043e \u043f\u0440\u0435\u0434\u043f\u0440\u0438\u044f\u0442\u0438\u0439 \u0432\u044b\u0440\u0430\u0437\u0438\u043b\u0438 \u043d\u0430\u043c\u0435\u0440\u0435\u043d\u0438\u044f \u043e \u043d\u0435\u043c\u0435\u0434\u043b\u0435\u043d\u043d\u043e\u043c \u0441\u043e\u0442\u0440\u0443\u0434\u043d\u0438\u0447\u0435\u0441\u0442\u0432\u0435, \u0437\u0430\u043b\u043e\u0436\u0438\u0432 \u043f\u0440\u043e\u0447\u043d\u0443\u044e \u043e\u0441\u043d\u043e\u0432\u0443 \u0434\u043b\u044f \u0431\u0443\u0434\u0443\u0449\u0435\u0433\u043e \u0440\u0430\u0441\u0448\u0438\u0440\u0435\u043d\u0438\u044f \u0433\u043b\u043e\u0431\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0440\u044b\u043d\u043a\u0430.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-uagb-image uagb-block-35ff1860 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-4.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-4.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-4.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-4.jpg\" alt=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-4\" class=\"uag-image-3333\" width=\"800\" height=\"600\" title=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-4\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-18a4de83 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-2.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-2.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-2.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-2.jpg\" alt=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-2\" class=\"uag-image-3331\" width=\"800\" height=\"600\" title=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-2\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<p>\u042d\u0442\u0430 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430 \u043f\u043e\u0441\u043b\u0443\u0436\u0438\u043b\u0430 \u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u043f\u043b\u0430\u0442\u0444\u043e\u0440\u043c\u043e\u0439 \u0434\u043b\u044f \u0434\u0435\u043c\u043e\u043d\u0441\u0442\u0440\u0430\u0446\u0438\u0438 \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u0445 \u043f\u0440\u0435\u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432 \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0438 Jinshiwan, \u043d\u043e \u0438 \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u043c \u043c\u043e\u0441\u0442\u043e\u043c \u0434\u043b\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u0433\u043e \u0441\u043e\u0442\u0440\u0443\u0434\u043d\u0438\u0447\u0435\u0441\u0442\u0432\u0430. \u0412 \u0434\u0430\u043b\u044c\u043d\u0435\u0439\u0448\u0435\u043c \u043c\u044b \u0431\u0443\u0434\u0435\u043c \u043f\u0440\u043e\u0434\u043e\u043b\u0436\u0430\u0442\u044c \u0443\u0434\u0435\u043b\u044f\u0442\u044c \u043e\u0441\u043e\u0431\u043e\u0435 \u0432\u043d\u0438\u043c\u0430\u043d\u0438\u0435 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u0438 \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0438 \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u043c \u0438\u043d\u043d\u043e\u0432\u0430\u0446\u0438\u044f\u043c, \u0447\u0442\u043e\u0431\u044b \u0432\u044b\u0432\u0435\u0441\u0442\u0438 \u043a\u0438\u0442\u0430\u0439\u0441\u043a\u0438\u0439 \u043e\u043f\u044b\u0442 \u043d\u0430 \u043c\u0438\u0440\u043e\u0432\u0443\u044e \u0430\u0440\u0435\u043d\u0443.<\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-90162228 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-1.jpg ,https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-1.jpg 780w, https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-1.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-1.jpg\" alt=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-1\" class=\"uag-image-3330\" width=\"800\" height=\"600\" title=\"\u041a\u0438\u0442\u0430\u0439\u0441\u043a\u0430\u044f \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0430\u044f \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043d\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430-1\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p>\u041c\u044b \u0438\u0441\u043a\u0440\u0435\u043d\u043d\u0435 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u0438\u043c \u0432\u0441\u0435\u0445 \u043f\u043e\u0441\u0435\u0442\u0438\u0442\u0435\u043b\u0435\u0439, \u043f\u0430\u0440\u0442\u043d\u0435\u0440\u043e\u0432 \u0438 \u0434\u0440\u0443\u0437\u0435\u0439, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0437\u0430\u0433\u043b\u044f\u043d\u0443\u043b\u0438 \u043a \u043d\u0430\u043c \u043d\u0430 \u0441\u0442\u0435\u043d\u0434!<br>\u041f\u0440\u0438\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u044f\u0441\u044c \u043d\u0430\u0448\u0435\u0439 \u043e\u0441\u043d\u043e\u0432\u043d\u043e\u0439 \u0444\u0438\u043b\u043e\u0441\u043e\u0444\u0438\u0438 \u201c\u0422\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u044f \u043f\u0440\u0435\u0432\u044b\u0448\u0435 \u0432\u0441\u0435\u0433\u043e, \u0441\u0435\u0440\u0432\u0438\u0441 \u043f\u0440\u0435\u0432\u044b\u0448\u0435 \u0432\u0441\u0435\u0433\u043e\u201d, \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f Jinshiwan \u043f\u0440\u043e\u0434\u043e\u043b\u0436\u0430\u0435\u0442 \u0432\u043d\u0435\u0434\u0440\u044f\u0442\u044c \u044d\u0442\u043e\u0442 \u043f\u0440\u0438\u043d\u0446\u0438\u043f \u0432 \u043a\u0430\u0436\u0434\u0443\u044e \u043d\u0430\u0443\u0447\u043d\u043e-\u0438\u0441\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u0435\u043b\u044c\u0441\u043a\u0443\u044e \u0438\u043d\u0438\u0446\u0438\u0430\u0442\u0438\u0432\u0443 \u0438 \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0438\u0435 \u0443\u0441\u043b\u0443\u0433, \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u044f \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u044c \u0438\u043d\u0444\u0440\u0430\u0441\u0442\u0440\u0443\u043a\u0442\u0443\u0440\u044b \u044d\u043d\u0435\u0440\u0433\u0435\u0442\u0438\u0447\u0435\u0441\u043a\u0438\u0445 \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u043f\u043e \u0432\u0441\u0435\u043c\u0443 \u043c\u0438\u0440\u0443!<\/p>","protected":false},"excerpt":{"rendered":"<p>The 8th China International Pipeline Conference (CIPC) &amp; Technology Equipment Exhibition has successfully concluded. At this grand gathering of industry elites and cutting-edge technologies, Beijing Jinshiwan Pipeline Technology Co., Ltd. attracted numerous domestic and international clients to its booth for in-depth consultations. As a high-tech enterprise specializing in oil &amp; gas pipeline maintenance and emergency [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[74],"tags":[76],"class_list":["post-3328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-jsw-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo! - JSW Pipeline Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pipetechservice.com\/ru\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo!\" \/>\n<meta property=\"og:description\" content=\"The 8th China International Pipeline Conference (CIPC) &amp; Technology Equipment Exhibition has successfully concluded. At this grand gathering of industry elites and cutting-edge technologies, Beijing Jinshiwan Pipeline Technology Co., Ltd. attracted numerous domestic and international clients to its booth for in-depth consultations. As a high-tech enterprise specializing in oil &amp; gas pipeline maintenance and emergency [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pipetechservice.com\/ru\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/\" \/>\n<meta property=\"og:site_name\" content=\"JSW Pipeline Service\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-10T05:50:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T01:59:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"570\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jasonsong889@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jasonsong889@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/\"},\"author\":{\"name\":\"jasonsong889@gmail.com\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/person\\\/c2f337d45f7612353b91c42331c72259\"},\"headline\":\"JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo!\",\"datePublished\":\"2025-08-10T05:50:49+00:00\",\"dateModified\":\"2026-06-20T01:59:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/China-International-Pipeline-Exhibition.jpg\",\"keywords\":[\"JSW News\"],\"articleSection\":[\"News\"],\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/\",\"name\":\"JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo! - JSW Pipeline Service\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/China-International-Pipeline-Exhibition.jpg\",\"datePublished\":\"2025-08-10T05:50:49+00:00\",\"dateModified\":\"2026-06-20T01:59:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/China-International-Pipeline-Exhibition.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/China-International-Pipeline-Exhibition.jpg\",\"width\":570,\"height\":360,\"caption\":\"China-International-Pipeline-Exhibition\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pipetechservice.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/\",\"name\":\"JSW Pipeline Service\",\"description\":\"Building It Better In Concrete\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pipetechservice.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#organization\",\"name\":\"Beijing Jinshiwan Pipeline Technology Co., Ltd.\",\"alternateName\":\"JSW\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pipetechservice.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.jpg\",\"width\":996,\"height\":296,\"caption\":\"Beijing Jinshiwan Pipeline Technology Co., Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pipetechservice.com\\\/#\\\/schema\\\/person\\\/c2f337d45f7612353b91c42331c72259\",\"name\":\"jasonsong889@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g\",\"caption\":\"jasonsong889@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/www.pipetechservice.com\"],\"url\":\"https:\\\/\\\/www.pipetechservice.com\\\/ru\\\/author\\\/jasonsong889gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JSW \u0437\u0430\u0432\u043e\u0435\u0432\u0430\u043b\u0430 \u043c\u0438\u0440\u043e\u0432\u043e\u0435 \u043f\u0440\u0438\u0437\u043d\u0430\u043d\u0438\u0435 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u0442\u0435\u0445\u043d\u0438\u0447\u0435\u0441\u043a\u043e\u0439 \u044d\u043a\u0441\u043f\u0435\u0440\u0442\u0438\u0437\u0435 \u043d\u0430 \u0443\u0441\u043f\u0435\u0448\u043d\u043e \u0437\u0430\u0432\u0435\u0440\u0448\u0438\u0432\u0448\u0435\u0439\u0441\u044f \u0432 2025 \u0433\u043e\u0434\u0443 \u041f\u0435\u043a\u0438\u043d\u0441\u043a\u043e\u0439 \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u0439 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0435 \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432! - JSW Pipeline Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pipetechservice.com\/ru\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/","og_locale":"ru_RU","og_type":"article","og_title":"JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo!","og_description":"The 8th China International Pipeline Conference (CIPC) &amp; Technology Equipment Exhibition has successfully concluded. At this grand gathering of industry elites and cutting-edge technologies, Beijing Jinshiwan Pipeline Technology Co., Ltd. attracted numerous domestic and international clients to its booth for in-depth consultations. As a high-tech enterprise specializing in oil &amp; gas pipeline maintenance and emergency [&hellip;]","og_url":"https:\/\/www.pipetechservice.com\/ru\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/","og_site_name":"JSW Pipeline Service","article_published_time":"2025-08-10T05:50:49+00:00","article_modified_time":"2026-06-20T01:59:47+00:00","og_image":[{"width":570,"height":360,"url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg","type":"image\/jpeg"}],"author":"jasonsong889@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jasonsong889@gmail.com","Est. reading time":"3 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#article","isPartOf":{"@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/"},"author":{"name":"jasonsong889@gmail.com","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/person\/c2f337d45f7612353b91c42331c72259"},"headline":"JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo!","datePublished":"2025-08-10T05:50:49+00:00","dateModified":"2026-06-20T01:59:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/www.pipetechservice.com\/#organization"},"image":{"@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg","keywords":["JSW News"],"articleSection":["News"],"inLanguage":"ru-RU","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/","url":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/","name":"JSW \u0437\u0430\u0432\u043e\u0435\u0432\u0430\u043b\u0430 \u043c\u0438\u0440\u043e\u0432\u043e\u0435 \u043f\u0440\u0438\u0437\u043d\u0430\u043d\u0438\u0435 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u0442\u0435\u0445\u043d\u0438\u0447\u0435\u0441\u043a\u043e\u0439 \u044d\u043a\u0441\u043f\u0435\u0440\u0442\u0438\u0437\u0435 \u043d\u0430 \u0443\u0441\u043f\u0435\u0448\u043d\u043e \u0437\u0430\u0432\u0435\u0440\u0448\u0438\u0432\u0448\u0435\u0439\u0441\u044f \u0432 2025 \u0433\u043e\u0434\u0443 \u041f\u0435\u043a\u0438\u043d\u0441\u043a\u043e\u0439 \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u0439 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0435 \u0442\u0440\u0443\u0431\u043e\u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432! - JSW Pipeline Service","isPartOf":{"@id":"https:\/\/www.pipetechservice.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#primaryimage"},"image":{"@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg","datePublished":"2025-08-10T05:50:49+00:00","dateModified":"2026-06-20T01:59:47+00:00","breadcrumb":{"@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#primaryimage","url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg","contentUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg","width":570,"height":360,"caption":"China-International-Pipeline-Exhibition"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pipetechservice.com\/jsw-wins-global-recognition-with-technical-expertise-at-successfully-concluded-2025-beijing-international-pipeline-expo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pipetechservice.com\/"},{"@type":"ListItem","position":2,"name":"JSW Wins Global Recognition with Technical Expertise at Successfully Concluded 2025 Beijing International Pipeline Expo!"}]},{"@type":"WebSite","@id":"https:\/\/www.pipetechservice.com\/#website","url":"https:\/\/www.pipetechservice.com\/","name":"JSW Pipeline Service","description":"\u0421\u0442\u0440\u043e\u0438\u0442\u044c \u043b\u0443\u0447\u0448\u0435 \u0438\u0437 \u0431\u0435\u0442\u043e\u043d\u0430","publisher":{"@id":"https:\/\/www.pipetechservice.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pipetechservice.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/www.pipetechservice.com\/#organization","name":"\u041f\u0435\u043a\u0438\u043d\u0441\u043a\u0430\u044f \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f Jinshiwan Pipeline Technology Co., Ltd.","alternateName":"JSW","url":"https:\/\/www.pipetechservice.com\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/07\/logo.jpg","contentUrl":"https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/07\/logo.jpg","width":996,"height":296,"caption":"Beijing Jinshiwan Pipeline Technology Co., Ltd."},"image":{"@id":"https:\/\/www.pipetechservice.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pipetechservice.com\/#\/schema\/person\/c2f337d45f7612353b91c42331c72259","name":"jasonsong889@gmail.com","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2249aded6ecc7f5a96f9dae5858eb37119c29a16dd4172684fa91d83a97ca0d0?s=96&d=mm&r=g","caption":"jasonsong889@gmail.com"},"sameAs":["https:\/\/www.pipetechservice.com"],"url":"https:\/\/www.pipetechservice.com\/ru\/author\/jasonsong889gmail-com\/"}]}},"spectra_custom_meta":{"_edit_lock":["1781920790:1"],"_thumbnail_id":["3329"],"_surecart_dashboard_logo_width":["180px"],"_surecart_dashboard_show_logo":["1"],"_surecart_dashboard_navigation_orders":["1"],"_surecart_dashboard_navigation_invoices":["1"],"_surecart_dashboard_navigation_subscriptions":["1"],"_surecart_dashboard_navigation_downloads":["1"],"_surecart_dashboard_navigation_billing":["1"],"_surecart_dashboard_navigation_account":["1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_elementor_edit_mode":[""],"_elementor_template_type":["wp-post"],"_elementor_data":[""],"_elementor_conditions":["a:0:{}"],"_edit_last":["1"],"_yoast_indexnow_last_ping":["1781920788"],"_yoast_wpseo_primary_category":["74"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_focuskeywords":[""],"_yoast_wpseo_keywordsynonyms":[""],"_yoast_wpseo_estimated-reading-time-minutes":["3"],"_elementor_version":["3.30.3"],"_elementor_pro_version":["3.5.1"],"_elementor_page_settings":[""],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:6;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_yoast_wpseo_schema_page_type":["WebPage"],"_yoast_wpseo_schema_article_type":["TechArticle"],"_uag_css_file_name":["uag-css-3328.css"],"_elementor_page_assets":["a:0:{}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:37085:\".wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-c8f13927.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c8f13927.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c8f13927.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c8f13927.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-c8f13927.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c8f13927.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-c8f13927.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c8f13927.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c3e59185.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c3e59185.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c3e59185.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c3e59185.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-c3e59185.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c3e59185.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-c3e59185.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c3e59185.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9a014ec6.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9a014ec6.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9a014ec6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-9a014ec6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9a014ec6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9a014ec6.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-35ff1860.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-35ff1860.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-35ff1860.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-35ff1860.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-35ff1860.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-35ff1860.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-35ff1860.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-35ff1860.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-18a4de83.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-18a4de83.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-18a4de83.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-18a4de83.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-18a4de83.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-18a4de83.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-18a4de83.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-18a4de83.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-90162228.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-90162228.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-90162228.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-90162228.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-90162228.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-90162228.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-90162228.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-90162228.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-c8f13927.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-c3e59185.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-9a014ec6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-35ff1860.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-18a4de83.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-90162228.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-c8f13927.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-c3e59185.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-9a014ec6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-35ff1860.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-18a4de83.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-90162228.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a8914a16 .uagb-heading-text{font-size: 22px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-355f2a37 .uagb-heading-text{font-size: 22px;margin-bottom: 15px;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d59ae4f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-9d59ae4f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 288px;height: auto;}}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-de36b878.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-de36b878.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bb4689b9.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-de36b878.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-bb4689b9.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-ab31a061.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ab31a061.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d17e4438.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d17e4438.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ca14edc7.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ca14edc7.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-acd89eda .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-acd89eda .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-acd89eda.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-wrap{margin-right: 15px;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-7e355c58 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-7e355c58.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:44:{i:0;s:14:\"core\/paragraph\";i:1;s:10:\"uagb\/image\";i:2;s:10:\"core\/group\";i:3;s:23:\"surecart\/slide-out-cart\";i:5;s:26:\"surecart\/cart-close-button\";i:6;s:19:\"surecart\/cart-count\";i:8;s:34:\"surecart\/slide-out-cart-line-items\";i:11;s:29:\"surecart\/cart-line-item-image\";i:15;s:29:\"surecart\/cart-line-item-title\";i:17;s:34:\"surecart\/cart-line-item-price-name\";i:18;s:31:\"surecart\/cart-line-item-variant\";i:19;s:28:\"surecart\/cart-line-item-note\";i:20;s:30:\"surecart\/cart-line-item-status\";i:23;s:38:\"surecart\/cart-line-item-scratch-amount\";i:24;s:30:\"surecart\/cart-line-item-amount\";i:25;s:32:\"surecart\/cart-line-item-interval\";i:27;s:29:\"surecart\/cart-line-item-trial\";i:28;s:28:\"surecart\/cart-line-item-fees\";i:31;s:32:\"surecart\/cart-line-item-quantity\";i:33;s:30:\"surecart\/cart-line-item-remove\";i:35;s:25:\"surecart\/cart-order-bumps\";i:36;s:35:\"surecart\/cart-order-bump-pagination\";i:37;s:44:\"surecart\/cart-order-bump-pagination-previous\";i:38;s:40:\"surecart\/cart-order-bump-pagination-next\";i:39;s:33:\"surecart\/cart-order-bump-template\";i:41;s:30:\"surecart\/cart-order-bump-image\";i:43;s:30:\"surecart\/cart-order-bump-title\";i:44;s:36:\"surecart\/cart-order-bump-description\";i:46;s:39:\"surecart\/cart-order-bump-scratch-amount\";i:47;s:31:\"surecart\/cart-order-bump-amount\";i:48;s:35:\"surecart\/cart-order-bump-add-button\";i:50;s:38:\"surecart\/slide-out-cart-items-subtotal\";i:52;s:37:\"surecart\/cart-subtotal-scratch-amount\";i:53;s:29:\"surecart\/cart-subtotal-amount\";i:54;s:36:\"surecart\/slide-out-cart-items-submit\";i:55;s:11:\"core\/search\";i:57;s:12:\"core\/heading\";i:58;s:17:\"core\/latest-posts\";i:59;s:30:\"woocommerce\/product-categories\";i:60;s:9:\"core\/list\";i:61;s:14:\"core\/list-item\";i:62;s:21:\"uagb\/advanced-heading\";i:63;s:14:\"uagb\/icon-list\";i:64;s:20:\"uagb\/icon-list-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1783850060\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg",570,360,false],"thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-150x150.jpg",150,150,true],"medium":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-300x189.jpg",300,189,true],"medium_large":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg",570,360,false],"large":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg",570,360,false],"1536x1536":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg",570,360,false],"2048x2048":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg",570,360,false],"trp-custom-language-flag":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg",18,12,false],"woocommerce_thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition.jpg",570,360,false],"woocommerce_gallery_thumbnail":["https:\/\/www.pipetechservice.com\/wp-content\/uploads\/2025\/08\/China-International-Pipeline-Exhibition-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"jasonsong889@gmail.com","author_link":"https:\/\/www.pipetechservice.com\/ru\/author\/jasonsong889gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"The 8th China International Pipeline Conference (CIPC) &amp; Technology Equipment Exhibition has successfully concluded. At this grand gathering of industry elites and cutting-edge technologies, Beijing Jinshiwan Pipeline Technology Co., Ltd. attracted numerous domestic and international clients to its booth for in-depth consultations. As a high-tech enterprise specializing in oil &amp; gas pipeline maintenance and emergency&hellip;","_links":{"self":[{"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/posts\/3328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/comments?post=3328"}],"version-history":[{"count":1,"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/posts\/3328\/revisions"}],"predecessor-version":[{"id":3337,"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/posts\/3328\/revisions\/3337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/media\/3329"}],"wp:attachment":[{"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/media?parent=3328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/categories?post=3328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pipetechservice.com\/ru\/wp-json\/wp\/v2\/tags?post=3328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}